{"id":14,"date":"2008-07-22T21:36:09","date_gmt":"2008-07-23T00:36:09","guid":{"rendered":"http:\/\/mundobibliotecario.wordpress.com\/?p=14"},"modified":"2008-07-22T21:36:09","modified_gmt":"2008-07-23T00:36:09","slug":"a-informacao-sempre-correu-solta","status":"publish","type":"post","link":"https:\/\/mundobibliotecario.com.br\/index.php\/2008\/07\/22\/a-informacao-sempre-correu-solta\/","title":{"rendered":"A informa\u00e7\u00e3o sempre correu solta"},"content":{"rendered":"<p>\u00c9 comum ouvir em diversos lugares, em v\u00e1rios textos que vivemos na Era da Informa\u00e7\u00e3o. Mas porque apenas agora a informa\u00e7\u00e3o tomou tamanha import\u00e2ncia a ponto de tornar-se nome de uma Era, de um momento hist\u00f3rico?<\/p>\n<p>Um primeiro ponto a ser considerado s\u00e3o as tecnologias da informa\u00e7\u00e3o. Nunca se viu, em qualquer outro per\u00edodo da hist\u00f3ria, a informa\u00e7\u00e3o correr solta como hoje. N\u00e3o que em outros tempos ela n\u00e3o fosse divulgada, por\u00e9m restringia-se a grupos sociais menores.\u00a0O fen\u00f4meno verificado hoje\u00a0s\u00f3 foi poss\u00edvel com o surgimento de celulares, televis\u00e3o, r\u00e1dio, internet, palmtops, computadores&#8230; tudo isso pode ser considerado tecnologia da informa\u00e7\u00e3o porque transmite informa\u00e7\u00e3o e\u00a0permite sua propaga\u00e7\u00e3o r\u00e1pida e ampla. \u00c9 fato que mais informa\u00e7\u00f5es chegam at\u00e9 as pessoas, mas\u00a0muito pouco do que realmente se deseja saber.\u00a0Assim,\u00a0a quantidade informa\u00e7\u00f5es produzidas \u00e9 diretamente proporcional a dificuldade de se achar uma uma que seja espec\u00edfica.<\/p>\n<p>Outro ponto: a informa\u00e7\u00e3o possui valor agregado, transformando-se num bem que pode gerar lucro. Um exemplo disso \u00e9 uma caso interessante que ouvi certa vez. Um supermercado notou que nos finais de semana eram vendidos dois itens nos finais de semana do que durante a semana. Tal fato ocorria com certa freq\u00fc\u00eancia, pois os pais sa\u00edam para as compras enquanto as m\u00e3es arrumavam a casa. Contudo,\u00a0nem sempre seguiam a lista de compras, mas nunca se esqueciam de dois itens: fraldas e cerveja. Levavam a fralda para que as m\u00e3es n\u00e3o brigassem depois (ai se esquecessem&#8230;) e a cerveja para acompanhar o futebol.\u00a0De posse dessa informa\u00e7\u00e3o, o supermercado deixou esses itens em corredores pr\u00f3ximos para vend\u00ea-los mais e, assim, lucrar mais.<\/p>\n<p>\u00c9 por essas e outras que vivemos na Era da Informa\u00e7\u00e3o.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00c9 comum ouvir em diversos lugares, em v\u00e1rios textos que vivemos na Era da Informa\u00e7\u00e3o. Mas porque apenas agora a informa\u00e7\u00e3o tomou tamanha import\u00e2ncia a ponto de tornar-se nome de uma Era, de um momento hist\u00f3rico? Um primeiro ponto a ser considerado s\u00e3o as tecnologias da informa\u00e7\u00e3o. Nunca se viu, em qualquer outro per\u00edodo da &#8230; <a title=\"A informa\u00e7\u00e3o sempre correu solta\" class=\"read-more\" href=\"https:\/\/mundobibliotecario.com.br\/index.php\/2008\/07\/22\/a-informacao-sempre-correu-solta\/\" aria-label=\"Read more about A informa\u00e7\u00e3o sempre correu solta\">Ler mais<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_mi_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"_jetpack_newsletter_access":"","footnotes":""},"categories":[3],"tags":[21,19,22],"class_list":["post-14","post","type-post","status-publish","format-standard","hentry","category-reflexoes","tag-era-da-informacao","tag-informacao","tag-tecnologia-da-informacao"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack-related-posts":[{"id":423,"url":"https:\/\/mundobibliotecario.com.br\/index.php\/2009\/03\/03\/emulador-universal-salva-informacao-digital-para-futuras-geracoes\/","url_meta":{"origin":14,"position":0},"title":"Emulador universal salva informa\u00e7\u00e3o digital para futuras gera\u00e7\u00f5es","author":"mundobibliotecario","date":"03\/03\/2009","format":false,"excerpt":"Reda\u00e7\u00e3o do Site Inova\u00e7\u00e3o Tecnol\u00f3gica 03\/03\/2009 Quem gosta de jogos de computadores mais antigos costuma ter uma cole\u00e7\u00e3o de emuladores quase t\u00e3o grande quanto a pr\u00f3pria cole\u00e7\u00e3o de games. Isso acontece porque cada emulador \u00e9 espec\u00edfico para uma plataforma, tanto de origem quanto de destino - um emulador que lhe\u2026","rel":"","context":"Em &quot;Not\u00edcias&quot;","block_context":{"text":"Not\u00edcias","link":"https:\/\/mundobibliotecario.com.br\/index.php\/category\/noticias\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":3701,"url":"https:\/\/mundobibliotecario.com.br\/index.php\/2015\/04\/01\/os-10-mitos-da-informacao-2\/","url_meta":{"origin":14,"position":1},"title":"Os 10 mitos da informa\u00e7\u00e3o (2)","author":"mundobibliotecario","date":"01\/04\/2015","format":false,"excerpt":"More information is always better. Yet too much leads to overload and thence to deliberate ignoring of inputs. \"Having information\" is not the same as \"being informed\", so increasing the flow of information does not always result in an informed person. Typically there is not a problem getting enough information\u2026","rel":"","context":"Em &quot;Reflex\u00f5es&quot;","block_context":{"text":"Reflex\u00f5es","link":"https:\/\/mundobibliotecario.com.br\/index.php\/category\/reflexoes\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1440,"url":"https:\/\/mundobibliotecario.com.br\/index.php\/2010\/09\/07\/mayana-zatz-informacao-sera-o-grande-desafio-etico-para-o-novo-homem\/","url_meta":{"origin":14,"position":2},"title":"Mayana Zatz: informa\u00e7\u00e3o ser\u00e1 o grande desafio \u00e9tico para o \u201cnovo homem\u201d","author":"mundobibliotecario","date":"07\/09\/2010","format":false,"excerpt":"O avan\u00e7o da Neuroci\u00eancia e da Engenharia Gen\u00e9tica nas \u00faltimas d\u00e9cadas desafiam cientistas e fil\u00f3sofos a entenderem o novo ser humano \u201cproduzido e manipulado\u201d em laborat\u00f3rio. N\u00e3o s\u00e3o apenas as quest\u00f5es cient\u00edficas que est\u00e3o na pauta, mas, tamb\u00e9m gigantescos desafios \u00e9ticos e sociais. Manipula\u00e7\u00e3o da mente, capacidade da mem\u00f3ria intelectual,\u2026","rel":"","context":"Em &quot;Not\u00edcias&quot;","block_context":{"text":"Not\u00edcias","link":"https:\/\/mundobibliotecario.com.br\/index.php\/category\/noticias\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":3502,"url":"https:\/\/mundobibliotecario.com.br\/index.php\/2014\/06\/08\/devemos-ser-ativos-em-nossa-propria-informacao\/","url_meta":{"origin":14,"position":3},"title":"Devemos ser ativos em nossa pr\u00f3pria informa\u00e7\u00e3o","author":"mundobibliotecario","date":"08\/06\/2014","format":false,"excerpt":"Informar-se n\u00e3o pode ser uma atitude passiva. Os meios de comunica\u00e7\u00e3o n\u00e3o s\u00e3o confi\u00e1veis: o cidad\u00e3o tem que aprender a verificar, ele mesmo, que fonte usar L'Ombelico del Mondo No blog L\u2019Ombelico de Mondo, o fundador do Le Monde Diplomatique, Ignacio Ramonet, analizou o papel da m\u00eddia no panorama internacional\u2026","rel":"","context":"Em &quot;Not\u00edcias&quot;","block_context":{"text":"Not\u00edcias","link":"https:\/\/mundobibliotecario.com.br\/index.php\/category\/noticias\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":3371,"url":"https:\/\/mundobibliotecario.com.br\/index.php\/2014\/01\/04\/a-ciencia-da-informacao-sob-a-otica-de-tefko-saracevic\/","url_meta":{"origin":14,"position":4},"title":"A Ci\u00eancia da Informa\u00e7\u00e3o sob a \u00f3tica de Tefko Saracevic","author":"mundobibliotecario","date":"04\/01\/2014","format":false,"excerpt":"No m\u00eas em que completa dois anos, o blog\u00a0Disserta\u00e7\u00e3o Sobre Divulga\u00e7\u00e3o Cient\u00edfica\u00a0entrevistou um dos fundadores e principais estudiosos da Ci\u00eancia da Informa\u00e7\u00e3o (CI).\u00a0O pesquisador croata Tefko Saracevic, 83 anos, falou sobre a realidade, as tend\u00eancias e as inquieta\u00e7\u00f5es contempor\u00e2neas da CI, assim como a respeito da contribui\u00e7\u00e3o do Brasil para\u2026","rel":"","context":"Em &quot;Not\u00edcias&quot;","block_context":{"text":"Not\u00edcias","link":"https:\/\/mundobibliotecario.com.br\/index.php\/category\/noticias\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":2710,"url":"https:\/\/mundobibliotecario.com.br\/index.php\/2012\/09\/09\/menos-informacao-por-favor\/","url_meta":{"origin":14,"position":5},"title":"Menos informa\u00e7\u00e3o, por favor","author":"mundobibliotecario","date":"09\/09\/2012","format":false,"excerpt":"5 de setembro de 2012|17h23|Tweet este Post Por Ag\u00eancias Segundo pesquisa, 60% dos usu\u00e1rios da web acham que as pessoas falam mais do que deveriam e sobre coisas que n\u00e3o interessam NOVA YORK \u2013 Uma pesquisa aponta que 60% dos adultos e adolescentes que usam tecnologia m\u00f3vel acham que os\u2026","rel":"","context":"Em &quot;Not\u00edcias&quot;","block_context":{"text":"Not\u00edcias","link":"https:\/\/mundobibliotecario.com.br\/index.php\/category\/noticias\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/blogs.estadao.com.br\/link\/files\/2011\/12\/scroll.jpg?resize=350%2C200","width":350,"height":200},"classes":[]}],"jetpack_likes_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pcbzwa-e","_links":{"self":[{"href":"https:\/\/mundobibliotecario.com.br\/index.php\/wp-json\/wp\/v2\/posts\/14","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mundobibliotecario.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mundobibliotecario.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mundobibliotecario.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/mundobibliotecario.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=14"}],"version-history":[{"count":0,"href":"https:\/\/mundobibliotecario.com.br\/index.php\/wp-json\/wp\/v2\/posts\/14\/revisions"}],"wp:attachment":[{"href":"https:\/\/mundobibliotecario.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=14"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mundobibliotecario.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=14"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mundobibliotecario.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=14"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}