{"id":2074,"date":"2011-06-11T15:40:24","date_gmt":"2011-06-11T18:40:24","guid":{"rendered":"http:\/\/mundobibliotecario.wordpress.com\/?p=2074"},"modified":"2020-07-21T23:22:28","modified_gmt":"2020-07-22T02:22:28","slug":"catalogos-e-open-archives","status":"publish","type":"post","link":"https:\/\/mundobibliotecario.com.br\/index.php\/2011\/06\/11\/catalogos-e-open-archives\/","title":{"rendered":"Cat\u00e1logos e Open Archives"},"content":{"rendered":"<p>James Weinheimer, autor do blog First Thus, publicou recentemente um podcast em que ele aborda a quest\u00e3o dos cat\u00e1logos e dos open archives, ou arquivos abertos.<\/p>\n<p>Achei interessante o trecho em que foi abordada a revis\u00e3o p\u00f3s-publica\u00e7\u00e3o existente no contexto dos open archives. Trata-se de uma pr\u00e1tica em que os leitores comentam os artigos dispon\u00edveis em um resposit\u00f3rio, por exemplo, que podem servir de base para uma revis\u00e3o e atualiza\u00e7\u00e3o pelo autor, mostrando um modelo de revis\u00e3o pelos pares ainda incomum, mas poss\u00edvel de ser realizado.<\/p>\n<p>Outro trecho que me chamou a aten\u00e7\u00e3o \u00e9 em rela\u00e7\u00e3o \u00e0 inclus\u00e3o dos materiais open archives em cat\u00e1logos de bibliotecas. Como se tratam de materiais dispon\u00edveis na web e que, s\u00f3 por isso, podem ser mais dif\u00edceis de serem recuperados, seria interessante que as bibliotecas passsassem a incluir esse tipo de material em seus cat\u00e1logos como forma de agregar valor a essa importante fonte de informa\u00e7\u00e3o.<\/p>\n<p>Vale a pena ouvir o podcast, que \u00e9 acompanhado pelo texto em ingl\u00eas e, portanto, uma \u00f3tima oportunidade para treinar o idioma!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>James Weinheimer, autor do blog First Thus, publicou recentemente um podcast em que ele aborda a quest\u00e3o dos cat\u00e1logos e dos open archives, ou arquivos abertos. Achei interessante o trecho em que foi abordada a revis\u00e3o p\u00f3s-publica\u00e7\u00e3o existente no contexto dos open archives. Trata-se de uma pr\u00e1tica em que os leitores comentam os artigos dispon\u00edveis &#8230; <a title=\"Cat\u00e1logos e Open Archives\" class=\"read-more\" href=\"https:\/\/mundobibliotecario.com.br\/index.php\/2011\/06\/11\/catalogos-e-open-archives\/\" aria-label=\"Read more about Cat\u00e1logos e Open Archives\">Ler mais<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_mi_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"_jetpack_newsletter_access":"","footnotes":""},"categories":[60],"tags":[598,601,767],"class_list":["post-2074","post","type-post","status-publish","format-standard","hentry","category-noticias","tag-catalogo-online","tag-opac","tag-open-archives"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack-related-posts":[{"id":8225,"url":"https:\/\/mundobibliotecario.com.br\/index.php\/2020\/12\/30\/o-library-explorer-do-internet-archive-torna-divertido-pesquisar-livros-online\/","url_meta":{"origin":2074,"position":0},"title":"O Library Explorer do Internet Archive torna divertido pesquisar livros online","author":"mundobibliotecario","date":"30\/12\/2020","format":false,"excerpt":"Fonte: Mashable Se voc\u00ea \u00e9 um nerd que sente falta de passar horas na biblioteca local, folheando milhares de t\u00edtulos e vagando pelas prateleiras, o\u00a0Library Explorer\u00a0pode ajudar a aliviar a tristeza.\u00a0Atualmente em beta, a interface permite que voc\u00ea navegue virtualmente em uma biblioteca \"f\u00edsica\". O projeto vem do\u00a0Internet Archive\u00a0- um\u2026","rel":"","context":"Em &quot;Not\u00edcias&quot;","block_context":{"text":"Not\u00edcias","link":"https:\/\/mundobibliotecario.com.br\/index.php\/category\/noticias\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":2549,"url":"https:\/\/mundobibliotecario.com.br\/index.php\/2012\/04\/13\/portal-reune-teses-de-todo-o-mundo\/","url_meta":{"origin":2074,"position":1},"title":"Portal re\u00fane teses de todo o mundo","author":"mundobibliotecario","date":"13\/04\/2012","format":false,"excerpt":"Site traz trabalhos como os do fil\u00f3sofo Edgar Morin TAGS:\u00a0Centro para Comunica\u00e7\u00e3o Cient\u00edfica Direta,\u00a0disserta\u00e7\u00f5es,\u00a0Edgar Morin,\u00a0HAL,\u00a0Open Archive Initiative,teses,\u00a0trabalhos cient\u00edficos O portal franc\u00eas HAL, desenvolvido pelo Centro para Comunica\u00e7\u00e3o Cient\u00edfica Direta, disponibiliza na rede mais de 200 mil trabalhos cient\u00edficos do mundo inteiro e de todas as \u00e1reas do conhecimento. O acesso\u2026","rel":"","context":"Em &quot;Not\u00edcias&quot;","block_context":{"text":"Not\u00edcias","link":"https:\/\/mundobibliotecario.com.br\/index.php\/category\/noticias\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/revistacult.uol.com.br\/home\/wp-content\/uploads\/2012\/04\/Edgar-Morin-2.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":2816,"url":"https:\/\/mundobibliotecario.com.br\/index.php\/2013\/01\/28\/consulte-enciclopedias-e-bibliotecas-virtuais-de-todo-o-mundo\/","url_meta":{"origin":2074,"position":2},"title":"Consulte enciclop\u00e9dias e bibliotecas virtuais de todo o mundo","author":"mundobibliotecario","date":"28\/01\/2013","format":false,"excerpt":"Plataformas oferecem conte\u00fados em texto, \u00e1udio e v\u00eddeo em diversos idiomas Milhares de arquivos e documentos hist\u00f3ricos em apenas alguns cliques. Foto: Reprodu\u00e7\u00e3o Em mar\u00e7o deste ano, a famosa Encycloapedia Britannica deixou de circular em papel e passou a atuar apenas no universo digital. Uma consequ\u00eancia do avan\u00e7o da internet\u2026","rel":"","context":"Em &quot;Not\u00edcias&quot;","block_context":{"text":"Not\u00edcias","link":"https:\/\/mundobibliotecario.com.br\/index.php\/category\/noticias\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":2297,"url":"https:\/\/mundobibliotecario.com.br\/index.php\/2011\/11\/02\/congresso-internacional-sibiusp-30-anos-o-futuro-do-conhecimento-universal-iii\/","url_meta":{"origin":2074,"position":3},"title":"Congresso Internacional SIBiUSP 30 anos: O Futuro do Conhecimento Universal (III)","author":"mundobibliotecario","date":"02\/11\/2011","format":false,"excerpt":"A terceira mesa-redonda foi intitulada \"O futuro da produ\u00e7\u00e3o cient\u00edfica e intectual\", que apresentou projetos e discuss\u00f5es em torno do tema acesso aberto (open access), t\u00e3o em voga atualmente. Antonio M. Cunha, da Universidade do Minho (Portugal), foi o primeiro integrante da mesa a falar. Iniciou colocando que a universidade\u2026","rel":"","context":"Em &quot;Eventos&quot;","block_context":{"text":"Eventos","link":"https:\/\/mundobibliotecario.com.br\/index.php\/category\/eventos\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":3637,"url":"https:\/\/mundobibliotecario.com.br\/index.php\/2014\/11\/12\/how-open-is-it-espetro-do-acesso-aberto\/","url_meta":{"origin":2074,"position":4},"title":"How open is it? Espetro do acesso aberto","author":"mundobibliotecario","date":"12\/11\/2014","format":false,"excerpt":"Divulgo abaixo o guia \"How open is it?\", publicado por SPARC, PLOS e OASPA. Segue um trecho do texto do documento: Como usar este guia Em 2002, a Iniciativa de Acesso Aberto de Budapeste definiu os princ\u00edpios b\u00e1sicos do Acesso Aberto pela primeira vez. Desde ent\u00e3o, milhares de revistas cient\u00edficas\u2026","rel":"","context":"Em &quot;Not\u00edcias&quot;","block_context":{"text":"Not\u00edcias","link":"https:\/\/mundobibliotecario.com.br\/index.php\/category\/noticias\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":4253,"url":"https:\/\/mundobibliotecario.com.br\/index.php\/2016\/04\/14\/versila-da-acesso-a-acervo-dos-melhores-centros-de-pesquisa\/","url_meta":{"origin":2074,"position":5},"title":"\u201cV\u00e9rsila\u201d d\u00e1 acesso a acervo dos melhores centros de pesquisa","author":"mundobibliotecario","date":"14\/04\/2016","format":false,"excerpt":"Assessoria de Comunica\u00e7\u00e3o 13-Abr-2016 Desenvolvida por pesquisadores da USP, a Biblioteca Digital V\u00e9rsila \u00e9 considerada a maior em acervo digital acad\u00eamico do hemisf\u00e9rio sul, e disponibiliza gratuitamente toda a produ\u00e7\u00e3o cient\u00edfica aberta dos melhores centros de pesquisa do mundo. Desde seu lan\u00e7amento, no final de 2015, a V\u00e9rsila j\u00e1 teve\u2026","rel":"","context":"Em &quot;Not\u00edcias&quot;","block_context":{"text":"Not\u00edcias","link":"https:\/\/mundobibliotecario.com.br\/index.php\/category\/noticias\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_likes_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pcbzwa-xs","_links":{"self":[{"href":"https:\/\/mundobibliotecario.com.br\/index.php\/wp-json\/wp\/v2\/posts\/2074","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mundobibliotecario.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mundobibliotecario.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mundobibliotecario.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/mundobibliotecario.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=2074"}],"version-history":[{"count":2,"href":"https:\/\/mundobibliotecario.com.br\/index.php\/wp-json\/wp\/v2\/posts\/2074\/revisions"}],"predecessor-version":[{"id":6282,"href":"https:\/\/mundobibliotecario.com.br\/index.php\/wp-json\/wp\/v2\/posts\/2074\/revisions\/6282"}],"wp:attachment":[{"href":"https:\/\/mundobibliotecario.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=2074"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mundobibliotecario.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=2074"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mundobibliotecario.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=2074"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}