{"id":2428,"date":"2012-02-04T19:28:09","date_gmt":"2012-02-04T22:28:09","guid":{"rendered":"http:\/\/mundobibliotecario.wordpress.com\/?p=2428"},"modified":"2020-07-21T23:20:47","modified_gmt":"2020-07-22T02:20:47","slug":"projeto-obriga-editoras-a-doar-livros-para-bibliotecas-estaduais","status":"publish","type":"post","link":"https:\/\/mundobibliotecario.com.br\/index.php\/2012\/02\/04\/projeto-obriga-editoras-a-doar-livros-para-bibliotecas-estaduais\/","title":{"rendered":"Projeto obriga editoras a doar livros para bibliotecas estaduais"},"content":{"rendered":"<p>04\/02\/2012 &#8211; Segundo autor da proposta, al\u00e9m dos problemas financeiros, existem tamb\u00e9m dificuldades decorrentes das limita\u00e7\u00f5es da estrutura de distribui\u00e7\u00e3o de livros no Brasil.<\/p>\n<p>A C\u00e2mara analisa o Projeto de Lei 3085\/12, do Senado, que obriga as editoras a realizar o dep\u00f3sito legal de pelo menos um exemplar de suas publica\u00e7\u00f5es na Biblioteca Nacional de Bras\u00edlia e em todas as bibliotecas estaduais e do Distrito Federal. Atualmente, a Lei 10.994\/04 prev\u00ea o dep\u00f3sito obrigat\u00f3rio apenas para a Biblioteca Nacional, localizada no Rio de Janeiro.<\/p>\n<p>O autor da proposta, senador Jos\u00e9 Sarney (PMDB-AP), diz que, apesar de sua relev\u00e2ncia, as bibliotecas p\u00fablicas brasileiras encontram enorme dificuldade de renova\u00e7\u00e3o e atualiza\u00e7\u00e3o de seus acervos. &#8220;O Brasil possui uma importante estrutura de bibliotecas sob responsabilidade dos estados, mas que padecem de subaproveitamento devido \u00e0 limita\u00e7\u00e3o de seus acervos.&#8221;<\/p>\n<p>Segundo Sarney, al\u00e9m dos problemas financeiros, existem tamb\u00e9m dificuldades decorrentes das limita\u00e7\u00f5es da estrutura de distribui\u00e7\u00e3o de livros no Brasil. &#8220;A concentra\u00e7\u00e3o das principais redes de livrarias nos grandes centros urbanos tem desestimulado a distribui\u00e7\u00e3o de produtos culturais para as cidades de menor porte e para as localidades mais distantes&#8221;, afirma.<\/p>\n<p>Tramita\u00e7\u00e3o<\/p>\n<p>O projeto tramita em car\u00e1ter conclusivo e ser\u00e1 analisado pelas comiss\u00f5es de Educa\u00e7\u00e3o e Cultura; e de Constitui\u00e7\u00e3o e Justi\u00e7a e de Cidadania.<\/p>\n<p>Dispon\u00edvel em: &lt;http:\/\/www.cmconsultoria.com.br\/vercmnews.php?codigo=55856&gt;. Acesso em: 4 fev. 2011.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>04\/02\/2012 &#8211; Segundo autor da proposta, al\u00e9m dos problemas financeiros, existem tamb\u00e9m dificuldades decorrentes das limita\u00e7\u00f5es da estrutura de distribui\u00e7\u00e3o de livros no Brasil. A C\u00e2mara analisa o Projeto de Lei 3085\/12, do Senado, que obriga as editoras a realizar o dep\u00f3sito legal de pelo menos um exemplar de suas publica\u00e7\u00f5es na Biblioteca Nacional de &#8230; <a title=\"Projeto obriga editoras a doar livros para bibliotecas estaduais\" class=\"read-more\" href=\"https:\/\/mundobibliotecario.com.br\/index.php\/2012\/02\/04\/projeto-obriga-editoras-a-doar-livros-para-bibliotecas-estaduais\/\" aria-label=\"Read more about Projeto obriga editoras a doar livros para bibliotecas estaduais\">Ler mais<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_mi_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"_jetpack_newsletter_access":"","footnotes":""},"categories":[60],"tags":[905,766,353,9],"class_list":["post-2428","post","type-post","status-publish","format-standard","hentry","category-noticias","tag-biblioteca-estadual","tag-doacao","tag-editora","tag-livro"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack-related-posts":[{"id":2346,"url":"https:\/\/mundobibliotecario.com.br\/index.php\/2011\/12\/03\/biblioteca-nacional-promove-divulgacao-de-lei-que-exige-envio-de-publicacoes-a-instituicao\/","url_meta":{"origin":2428,"position":0},"title":"Biblioteca Nacional promove divulga\u00e7\u00e3o de lei que exige envio de publica\u00e7\u00f5es \u00e0 Institui\u00e7\u00e3o","author":"mundobibliotecario","date":"03\/12\/2011","format":false,"excerpt":"A Biblioteca Nacional (BN) est\u00e1 intensificando, desde o in\u00edcio deste m\u00eas, a divulga\u00e7\u00e3o da lei de Dep\u00f3sito Legal, sancionada em 2004, e modificada no ano passado, que tem como objetivo exigir a remessa \u00e0 BN de pelo menos um exemplar de todas as publica\u00e7\u00f5es produzidas no Brasil. De acordo com\u2026","rel":"","context":"Em &quot;Not\u00edcias&quot;","block_context":{"text":"Not\u00edcias","link":"https:\/\/mundobibliotecario.com.br\/index.php\/category\/noticias\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":3090,"url":"https:\/\/mundobibliotecario.com.br\/index.php\/2013\/04\/21\/marta-suplicy-tira-politicas-de-livro-e-leitura-da-biblioteca-nacional\/","url_meta":{"origin":2428,"position":1},"title":"Marta Suplicy tira pol\u00edticas de livro e leitura da Biblioteca Nacional","author":"mundobibliotecario","date":"21\/04\/2013","format":false,"excerpt":"Folha de S. Paulo - 11\/04\/13 As pol\u00edticas de livro e leitura do pa\u00eds deixar\u00e3o de ser atribui\u00e7\u00e3o da Funda\u00e7\u00e3o Biblioteca Nacional (FBN) e voltar\u00e3o \u00e0 estrutura do Minist\u00e9rio da Cultura, em Bras\u00edlia. A decis\u00e3o da ministra Marta Suplicy foi consolidada na \u00faltima segunda-feira, quando Jos\u00e9 Castilho Marques Neto, presidente\u2026","rel":"","context":"Em &quot;Not\u00edcias&quot;","block_context":{"text":"Not\u00edcias","link":"https:\/\/mundobibliotecario.com.br\/index.php\/category\/noticias\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":2744,"url":"https:\/\/mundobibliotecario.com.br\/index.php\/2012\/11\/04\/biblioteca-digital-de-pernambuco-sera-lancada-em-breve\/","url_meta":{"origin":2428,"position":2},"title":"Biblioteca Digital de Pernambuco ser\u00e1 lan\u00e7ada em breve","author":"mundobibliotecario","date":"04\/11\/2012","format":false,"excerpt":"Jornal do Brasil Antonio Campos O Instituto Maximiano Campos (IMC) e a ARC - Ind\u00fastrias Criativas estar\u00e3o lan\u00e7ando, em breve, o projeto Biblioteca Digital de Pernambuco. Ser\u00e1 uma biblioteca virtual em nuvem de livros digitais. O foco ser\u00e3o os autores pernambucanos, mas n\u00e3o um ambiente exclusivo deles. Ser\u00e1 lan\u00e7ada a\u2026","rel":"","context":"Em &quot;Not\u00edcias&quot;","block_context":{"text":"Not\u00edcias","link":"https:\/\/mundobibliotecario.com.br\/index.php\/category\/noticias\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":9565,"url":"https:\/\/mundobibliotecario.com.br\/index.php\/2021\/10\/25\/comissao-aprova-projeto-que-obriga-editoras-a-destinarem-livros-desatualizados-de-direito-para-reciclagem\/","url_meta":{"origin":2428,"position":3},"title":"Comiss\u00e3o aprova projeto que obriga editoras a destinarem livros desatualizados de Direito para reciclagem","author":"mundobibliotecario","date":"25\/10\/2021","format":false,"excerpt":"Erika Kokay recomendou a aprova\u00e7\u00e3o da proposta A Comiss\u00e3o de Cultura da C\u00e2mara dos Deputados aprovou o Projeto de Lei\u00a0 624\/20, que obriga as editoras de livros de Direito a destinarem para a reciclagem as obras desatualizadas n\u00e3o comercializadas. O descumprimento da medida sujeitar\u00e1 a editora ao pagamento de multa\u2026","rel":"","context":"Em &quot;Not\u00edcias&quot;","block_context":{"text":"Not\u00edcias","link":"https:\/\/mundobibliotecario.com.br\/index.php\/category\/noticias\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/mundobibliotecario.com.br\/wp-content\/uploads\/2021\/10\/livro-direito.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":4447,"url":"https:\/\/mundobibliotecario.com.br\/index.php\/2017\/01\/03\/lei-obriga-escolas-a-ter-biblioteca-bibliotecario-e-um-livro-por-aluno\/","url_meta":{"origin":2428,"position":4},"title":"Lei obriga escolas a ter biblioteca, bibliotec\u00e1rio e um livro por aluno","author":"mundobibliotecario","date":"03\/01\/2017","format":false,"excerpt":"O Projeto de Lei que obriga toda escola a ter biblioteca, bibliotec\u00e1rio e, no m\u00ednimo, um livro por aluno, de autoria do deputado estadual Jos\u00e9 Ricardo Wendling (PT), foi promulgado nesta quinta-feira (22) pelo plen\u00e1rio da Assembleia Legislativa do Amazonas (Aleam), passando a vigorar na data da publica\u00e7\u00e3o. A proposta\u2026","rel":"","context":"Em &quot;Not\u00edcias&quot;","block_context":{"text":"Not\u00edcias","link":"https:\/\/mundobibliotecario.com.br\/index.php\/category\/noticias\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":2641,"url":"https:\/\/mundobibliotecario.com.br\/index.php\/2012\/07\/03\/gabinete-de-leitura-recebe-1o-remessa-de-livros-da-biblioteca-nacional\/","url_meta":{"origin":2428,"position":5},"title":"Gabinete de Leitura recebe 1\u00ba remessa de livros da Biblioteca Nacional","author":"mundobibliotecario","date":"03\/07\/2012","format":false,"excerpt":"Contemplados com o projeto de amplia\u00e7\u00e3o de acervos de bibliotecas, da Biblioteca Nacional, o Gabinete de Leitura Sorocabano (GLS) recebeu, na \u00faltima sexta-feira, a primeira remessa dos 440 novos livros que compor\u00e3o o seu acervo. \"Recebemos em torno de 150 livros dos 440 pedidos. Os livros foram entregues pela Livraria\u2026","rel":"","context":"Em &quot;Not\u00edcias&quot;","block_context":{"text":"Not\u00edcias","link":"https:\/\/mundobibliotecario.com.br\/index.php\/category\/noticias\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_likes_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pcbzwa-Da","_links":{"self":[{"href":"https:\/\/mundobibliotecario.com.br\/index.php\/wp-json\/wp\/v2\/posts\/2428","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mundobibliotecario.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mundobibliotecario.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mundobibliotecario.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/mundobibliotecario.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=2428"}],"version-history":[{"count":1,"href":"https:\/\/mundobibliotecario.com.br\/index.php\/wp-json\/wp\/v2\/posts\/2428\/revisions"}],"predecessor-version":[{"id":6177,"href":"https:\/\/mundobibliotecario.com.br\/index.php\/wp-json\/wp\/v2\/posts\/2428\/revisions\/6177"}],"wp:attachment":[{"href":"https:\/\/mundobibliotecario.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=2428"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mundobibliotecario.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=2428"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mundobibliotecario.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=2428"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}