{"id":3514,"date":"2014-06-23T10:29:10","date_gmt":"2014-06-23T13:29:10","guid":{"rendered":"http:\/\/mundobibliotecario.wordpress.com\/?p=3514"},"modified":"2014-06-23T10:29:10","modified_gmt":"2014-06-23T13:29:10","slug":"morre-em-olinda-o-pesquisador-edson-nery-da-fonseca","status":"publish","type":"post","link":"https:\/\/mundobibliotecario.com.br\/index.php\/2014\/06\/23\/morre-em-olinda-o-pesquisador-edson-nery-da-fonseca\/","title":{"rendered":"Morre em Olinda o pesquisador Edson Nery da Fonseca"},"content":{"rendered":"<p>\u00c9 com pesar que publico a not\u00edcia abaixo.<\/p>\n<p>***<\/p>\n<p>Bibliotec\u00e1rio e professor universit\u00e1rio era especialista na obra de Gilberto Freyre<\/p>\n<p><span class=\"bluelight\">Publica\u00e7\u00e3o:<\/span>\u00a022\/06\/2014 12:36\u00a0<span class=\"bluelight\">Atualiza\u00e7\u00e3o:<\/span>\u00a022\/06\/2014 16:42<\/p>\n<div class=\"news_body\">\n<div class=\"font_change\">\n<div id=\"abanoticia\">\n<div>\n<table class=\"image center\">\n<tbody>\n<tr>\n<td><img decoding=\"async\" title=\"Foto: Juliana Leitao\/DP\/DAPress\" src=\"http:\/\/imgsapp.diariodepernambuco.com.br\/app\/noticia_127983242361\/2014\/06\/22\/511709\/20140622133122528007e.jpg\" alt=\"Foto: Juliana Leitao\/DP\/DAPress\" border=\"0\" \/><\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td class=\"zebra\">Foto: Juliana Leitao\/DP\/DAPress<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/div>\n<div>Morreu, aos 92 anos, por volta das 8h da manh\u00e3 deste domingo (22), o pesquisador e professor pernambucano Edson Nery da Fonseca, uma refer\u00eancia na biblioteconomia brasileira. Ele faleu em decorr\u00eancia de infec\u00e7\u00f5es pulmonar e urin\u00e1ria, na pr\u00f3pria casa, em Olinda, onde recebia atendimento hospitalar. Nesta segunda-feira, a partir das 9h, ser\u00e1 realizada \u00a0missa no Mosteiro de S\u00e3o Bento e, em seguida, o corpo segue para ser sepultado no Cemit\u00e9rio dos Ingleses.\n<\/div>\n<div>&#8220;\u00c9 uma perda imensa, mas acredito que ele viveu em plenitude. Foi um homem intenso. Edson Nery da Fonseca foi um homem de cultura exemplar e, sem d\u00favida, um dos maiores, ou talvez o maior conhecedor do Brasil de Gilberto Freyre. Ele tinha uma mem\u00f3ria extraordin\u00e1ria. Al\u00e9m de gostar da obra do soci\u00f3logo, de ter uma interpreta\u00e7\u00e3o l\u00facida, tamb\u00e9m foi um grande amigo de Gilberto, ent\u00e3o s\u00e3o duas coisas que se complementam&#8221;, comentou a antrop\u00f3loga e presidente da Academia Pernambucana de Letras, F\u00e1tima Quintas.<\/div>\n<div>\nPor meio de sua conta no twitter, o ex-ministro da Integra\u00e7\u00e3o Nacional, Fernando Bezerra Coelho, lamentou a morte do pesquisador. &#8220;A obra de Edson Nery estar\u00e1 sempre na estante dos grandes pernambucanos que honram a nossa terra e levam o pensamento de Pernambuco para o mundo&#8221;.<\/p>\n<p><strong>ENTREVISTA<\/strong><\/div>\n<div>\n<div>Em dezembro do ano passado, Edson Nery prestou depoimento ao\u00a0<em>Viver<\/em>\u00a0por ocasi\u00e3o dos 80 \u00a0anos da obra<em>\u00a0Casa Grande &amp; Senzala<\/em>, de Gilberto Freyre, cuja obra era uma especialidade do pesquisador. Os dois tamb\u00e9m foram amigos pessoais por mais de 40 anos.<\/div>\n<\/div>\n<div>\n<div><\/div>\n<\/div>\n<div><strong>Releia o depoimento dado por Edson Nery ao\u00a0<em>Viver:\u00a0<\/em><\/strong><\/div>\n<div><\/div>\n<div>&#8220;Para a minha gera\u00e7\u00e3o, Casa-grande e senzala foi de grande import\u00e2ncia. Eu sempre tinha escutado falar mal da obra no Col\u00e9gio N\u00f3brega, onde estudei. Comecei a ler o livro em 1940, quando um professor meu disse disse que ter\u00edamos como primeiro assunto o Brasil, e que para conhecer o pa\u00eds \u00e9 preciso ler o que se escreve sobre ele. Fiquei entusiasmado com o livro e li toda a obra de Freyre. At\u00e9 que fui a Apipucos conhec\u00ea-lo e passei a frequentar quase diariamente a casa dele&#8221;.<\/div>\n<div><\/div>\n<div>[youtube https:\/\/www.youtube.com\/watch?v=pV1zC_B2Rls]<\/div>\n<div><\/div>\n<div>\n<div><strong>TRAJET\u00d3RIA<\/strong><\/div>\n<div>Edson Nery da Fonseca ingressou na Faculdade de Direito do Recife, mas interrompeu o curso para servir o Ex\u00e9rcito. Somente alguns anos depois, em 1946, se formaria no curso fundamental de biblioteconomia oferecido pela Biblioteca Nacional do Rio de Janeiro. Ainda na d\u00e9cada de 1940, atuou como jornalista liter\u00e1rio no\u00a0<strong>Diario de Pernambuco.<\/strong><\/p>\n<p>Posteriormente, participou da funda\u00e7\u00e3o da Universidade de Bras\u00edlia e de v\u00e1rios cursos de gradua\u00e7\u00e3o e p\u00f3s-gradua\u00e7\u00e3o em biblioteconomia, inclusive no Recife. Aqui ele instalou o primeiro curso de biblioteconomia do Nordeste. Em outros estados, atuou na organiza\u00e7\u00e3o de acervos de in\u00fameras institui\u00e7\u00f5es.<\/p>\n<table class=\"image center\">\n<tbody>\n<tr>\n<td><img decoding=\"async\" title=\"Foto: Nando Chiappetta\/Esp.DP\/D.A Press. \" src=\"http:\/\/imgsapp.diariodepernambuco.com.br\/app\/noticia_127983242361\/2014\/06\/22\/511709\/20140622133132836023a.jpg\" alt=\"Foto: Nando Chiappetta\/Esp.DP\/D.A Press. \" border=\"0\" \/><\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td class=\"zebra\">Foto: Nando Chiappetta\/Esp.DP\/D.A Press.<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/div>\n<\/div>\n<div>Mas a atua\u00e7\u00e3o de Nery da Fonseca n\u00e3o se restringe ao Brasil. Ele foi respons\u00e1veis por organizar acervos em outros pa\u00edses, como quando trabalhou como consultor da Biblioteca do Congresso dos EUA.<\/p>\n<p>Foi condecorado com os t\u00edtulos de professor em\u00e9rito da Universidade de Bras\u00edlia e Doutor Honoris Causa pela Universidade Federal de Pernambuco.<\/p><\/div>\n<div>\n<div><\/div>\n<div><strong>ASSISTA A UM TRECHO DA PARTICIPA\u00c7\u00c3O DE EDSON NERY DA FONSECA NA FESTA LITER\u00c1RIA INTERNACIONAL DE PARATY, EM 2009<\/strong><\/div>\n<div><\/div>\n<div>[youtube https:\/\/www.youtube.com\/watch?v=t9e1ke_BmHQ]<\/div>\n<div>\nAl\u00e9m de Gilberto Freyre, Edson Nery da Fonseca conviveu com v\u00e1rios intelectuais que marcaram a cultura de Pernambuco e do Brasil. Foi pr\u00f3ximo de Manuel Bandeira, \u00a0Jo\u00e3o Cabral de Melo Neto, Otto Carpeaux, Antonio Houaiss, Jos\u00e9 Lins do Rego, Rubens Borba de Moraes. Do poeta pernambucano Mauro Mota, que escreveu um poema em homenagem a Edson Nery. Confira:<\/p>\n<p><em>O C\u00e3o<\/em><\/p>\n<div>(A Edson Nery da Fonseca)<\/div>\n<div><\/div>\n<div>\u00c9 um c\u00e3o negro. \u00c9 talvez o pr\u00f3prio C\u00e3o<\/div>\n<div>assombrado e fazendo assombra\u00e7\u00e3o.<\/div>\n<div>Estra\u00e7alha o sil\u00eancio com seus uivos.<\/div>\n<div>A espada \u00edgnea do olhar na escurid\u00e3o<\/div>\n<div>separa a noite, abre um canal no escuro.<\/div>\n<div>C\u00e3o da Constela\u00e7\u00e3o do Grande C\u00e3o,<\/div>\n<div>tombado no quintal, espreita o pulo:<\/div>\n<div>duendes, fantasmas de ladr\u00e3o no muro.<\/div>\n<div><\/div>\n<div>O latido ancestral liberta a fome<\/div>\n<div>de tempo, e o c\u00e3o, presa do faro, come<\/div>\n<div>o medo e a treva. Agita-se, devora<\/div>\n<div><\/div>\n<div>sua ra\u00e7\u00e3o de cor. Pois, louco e uivante,<\/div>\n<div>lambe os pontos cardeais, morde o levante<\/div>\n<div>e bebe o sangue matinal da aurora.<\/div>\n<div>\n<table class=\"image center\">\n<tbody>\n<tr>\n<td><img decoding=\"async\" title=\"Foto: Fliporto\/divulga\u00e7\u00e3o\" src=\"http:\/\/imgsapp.diariodepernambuco.com.br\/app\/noticia_127983242361\/2014\/06\/22\/511709\/20140622141113413629a.jpg\" alt=\"Foto: Fliporto\/divulga\u00e7\u00e3o\" border=\"0\" \/><\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td class=\"zebra\">Foto: Fliporto\/divulga\u00e7\u00e3o<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>Em 2013, Edson Nery foi um dos homenageados da Festa Liter\u00e1ria Internacional de Pernambuco (Fliporto).\n<\/p><\/div>\n<\/div>\n<div><strong>OBRA<\/strong><\/div>\n<\/div>\n<div>Veja alguns dos livros lan\u00e7ados por Edson Nery da Fonseca:<\/div>\n<div><em>Ser ou n\u00e3o ser bibliotec\u00e1rio e outros manifestos contra a rotina<\/em>(Associa\u00e7\u00e3o dos Bibliotec\u00e1rios do Distrito Federal, 1988).<\/div>\n<div><\/div>\n<div><em>Tr\u00eas conceitos de tempo na po\u00e9tica bandeiriana\u00a0<\/em>(Governo do Estado de Pernambuco, Secretaria de Turismo, Cultura e Esportes\/FUNDARPE, 1989).<\/div>\n<div><\/div>\n<div><em>O Recife de Manuel Bandeira\u00a0<\/em>(Pool Editorial, 1986).<\/div>\n<div><\/div>\n<div><em>Problemas brasileiros de documenta\u00e7\u00e3o\u00a0<\/em>(Instituto Brasileiro de Informa\u00e7\u00e3o em Ci\u00eancia e Tecnologia, 1988).<\/div>\n<div><\/div>\n<div><em>A biblioteca escolar e a crise da educa\u00e7\u00e3o\u00a0<\/em>\u00a0(Livraria Pioneira Editora, 1983).<\/div>\n<div><\/div>\n<div><em>Um livro completo meio s\u00e9culo (<\/em>Editora Massangana, Funda\u00e7\u00e3o Joaquim Nabuco, 1983).<\/div>\n<div><\/div>\n<div><em>Gilberto Freyre de A a Z\u00a0<\/em>\u00a0(Minist\u00e9rio da Cultura, Funda\u00e7\u00e3o Biblioteca Nacional, Departamento Nacional do Livro, Z\u00e9 Mario Editor, 2002).<\/div>\n<div><\/div>\n<div><em>O Recife revisitado\u00a0<\/em>(EDUFRN, Editora da UFRN, 2002).<\/div>\n<div><\/div>\n<div><em>Alumbramentos e perplexidades\u00a0<\/em>(ARX, 2002).<\/div>\n<div><\/div>\n<div><em>A biblioteconomia brasileira no contexto mundial (<\/em>Edi\u00e7\u00f5es Tempo Brasileiro, em conv\u00eanio com o Instituto Nacional do Livro, Minist\u00e9rio da Educa\u00e7\u00e3o e Cultura, 1979).<\/div>\n<div><\/div>\n<div><em>Distrito Federal \u00a0<\/em>(Bloch Educa\u00e7\u00e3o, 1976).<\/div>\n<div><\/div>\n<div><em>Conserva\u00e7\u00e3o de bibliotecas e arquivos em regi\u00f5es tropicais\u00a0<\/em>(Edi\u00e7\u00f5es ABDF, 1975).<\/div>\n<div><em>\u00a0<\/em><\/div>\n<div><em>O Grande sedutor: escritos sobre Gilberto Freyre de 1945 at\u00e9 hoje<\/em>\u00a0(Cassar\u00e1 Editora, 2011)<\/div>\n<div><\/div>\n<div><em>Problemas de comunica\u00e7\u00e3o da informa\u00e7\u00e3o cientifica\u00a0<\/em>(Thesaurus Editora, 1973).<\/div>\n<div><\/div>\n<div><em>Bibliografia de obras de referencia pernambucanas\u00a0<\/em>(Imprensa Universit\u00e1ria, 1964).<\/div>\n<div><\/div>\n<div><em>Em torno de Gilberto Freyre por Edson Nery da Fonseca\u00a0<\/em>(Funda\u00e7\u00e3o Joaquim Nabuco, Editora Massangana, 2007).<\/div>\n<div><\/div>\n<div><em>Introdu\u00e7\u00e3o \u00e0 Biblioteconomia\u00a0<\/em>(Briquet de Lemos, 2007).<\/div>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>\u00c9 com pesar que publico a not\u00edcia abaixo. *** Bibliotec\u00e1rio e professor universit\u00e1rio era especialista na obra de Gilberto Freyre Publica\u00e7\u00e3o:\u00a022\/06\/2014 12:36\u00a0Atualiza\u00e7\u00e3o:\u00a022\/06\/2014 16:42 Foto: Juliana Leitao\/DP\/DAPress Morreu, aos 92 anos, por volta das 8h da manh\u00e3 deste domingo (22), o pesquisador e professor pernambucano Edson Nery da Fonseca, uma refer\u00eancia na biblioteconomia brasileira. Ele faleu &#8230; <a title=\"Morre em Olinda o pesquisador Edson Nery da Fonseca\" class=\"read-more\" href=\"https:\/\/mundobibliotecario.com.br\/index.php\/2014\/06\/23\/morre-em-olinda-o-pesquisador-edson-nery-da-fonseca\/\" aria-label=\"Read more about Morre em Olinda o pesquisador Edson Nery da Fonseca\">Ler mais<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_mi_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"_jetpack_newsletter_access":"","footnotes":""},"categories":[60],"tags":[495,653],"class_list":["post-3514","post","type-post","status-publish","format-standard","hentry","category-noticias","tag-edson-nery-da-fonseca","tag-falecimento"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack-related-posts":[{"id":1015,"url":"https:\/\/mundobibliotecario.com.br\/index.php\/2009\/12\/16\/polemica-e-biblioteconomia-espelham-obra-de-edson-nery-da-fonseca\/","url_meta":{"origin":3514,"position":0},"title":"Pol\u00eamica e biblioteconomia espelham obra de Edson Nery da Fonseca","author":"mundobibliotecario","date":"16\/12\/2009","format":false,"excerpt":"29\/06\/2009 -19h47 TERESA CHAVES Colabora\u00e7\u00e3o para a Folha Online Um pernambucano biblioteconomista, que quase foi militar, monge, e que hoje \u00e9 considerado um dos maiores especialistas do Brasil na obra do soci\u00f3logo Gilberto Freyre (1900-1987), o autor de \"Casa Grande & Senzala\", um dos livros mais importantes da historiografia brasileira.\u2026","rel":"","context":"Em &quot;Not\u00edcias&quot;","block_context":{"text":"Not\u00edcias","link":"https:\/\/mundobibliotecario.com.br\/index.php\/category\/noticias\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":2726,"url":"https:\/\/mundobibliotecario.com.br\/index.php\/2012\/10\/04\/o-memorialista\/","url_meta":{"origin":3514,"position":1},"title":"O memorialista","author":"mundobibliotecario","date":"04\/10\/2012","format":false,"excerpt":"As amizades e os livros de Edson Nery da Fonseca por CAROL PIRES O carrilh\u00e3o mais sonoro de Olinda \u00e9 o da Bas\u00edlica de S\u00e3o Bento. Quando anuncia 18 horas, o bibliotec\u00e1rio Edson Nery da Fonseca pede licen\u00e7a e p\u00f5e-se a rezar \u2013 primeiro, o Angelus; depois, \u201cUbiquidade\u201d, um poema\u2026","rel":"","context":"Em &quot;Not\u00edcias&quot;","block_context":{"text":"Not\u00edcias","link":"https:\/\/mundobibliotecario.com.br\/index.php\/category\/noticias\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":4995,"url":"https:\/\/mundobibliotecario.com.br\/index.php\/2018\/08\/29\/fala-bibliotecaria-10-classicos-de-biblioteconomia-por-gabriela-pedrao\/","url_meta":{"origin":3514,"position":2},"title":"Fala, Bibliotec\u00e1ria: 10 cl\u00e1ssicos de Biblioteconomia! por Gabriela Pedr\u00e3o","author":"mundobibliotecario","date":"29\/08\/2018","format":false,"excerpt":"http:\/\/www.youtube.com\/watch?v=c5zhkg8cgAY - Introdu\u00e7\u00e3o \u00c0 Biblioteconomia + A Biblioteconomia brasileira no contexto mundial (Edson Nery da Fonseca) - Miss\u00e3o do bibliotec\u00e1rio (Ortega y Gasset) - As 5 leis da Biblioteconomia (Ranganathan) - Introdu\u00e7\u00e3o \u00e0 cataloga\u00e7\u00e3o + O que fazem os bibliotec\u00e1rios (Eliane Mey) - Hist\u00f3ria da Biblioteconomia brasileira (C\u00e9sar Augusto Castro)\u2026","rel":"","context":"Em &quot;Not\u00edcias&quot;","block_context":{"text":"Not\u00edcias","link":"https:\/\/mundobibliotecario.com.br\/index.php\/category\/noticias\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/img.youtube.com\/vi\/c5zhkg8cgAY\/0.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":3594,"url":"https:\/\/mundobibliotecario.com.br\/index.php\/2014\/09\/30\/pesquisadores-ja-tem-acesso-a-informacoes-protegidas-do-inep\/","url_meta":{"origin":3514,"position":3},"title":"Pesquisadores j\u00e1 t\u00eam acesso a informa\u00e7\u00f5es protegidas do Inep","author":"mundobibliotecario","date":"30\/09\/2014","format":false,"excerpt":"Assessoria de Comunica\u00e7\u00e3o 29-Set-2014 Consultores, professores e pesquisadores j\u00e1 podem pedir informa\u00e7\u00f5es educacionais sobre a base de dados protegidos do Instituto Nacional de Estudos e Pesquisas Educacionais An\u00edsio Teixeira (Inep). Antes, o acesso era restrito \u00e0 base p\u00fablica. Na segunda-feira, 22, portaria do Inep divulgou as normas exigidas para pedidos\u2026","rel":"","context":"Em &quot;Not\u00edcias&quot;","block_context":{"text":"Not\u00edcias","link":"https:\/\/mundobibliotecario.com.br\/index.php\/category\/noticias\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":294,"url":"https:\/\/mundobibliotecario.com.br\/index.php\/2009\/01\/19\/palestra-seguranca-da-informacao-perspectivas-para-2009-e-o-futuro\/","url_meta":{"origin":3514,"position":4},"title":"Palestra \u201cSeguran\u00e7a da Informa\u00e7\u00e3o: Perspectivas para 2009 e o Futuro\u201d","author":"mundobibliotecario","date":"19\/01\/2009","format":false,"excerpt":"O Senac Campinas realiza, dia 27 de janeiro, a palestra \u201cSeguran\u00e7a da Informa\u00e7\u00e3o: Perspectivas para 2009 e o Futuro\u201d. O evento tem in\u00edcio \u00e0s 19h30 e a entrada \u00e9 franca. Quais devem ser as expectativas para 2009 em rela\u00e7\u00e3o \u00e0 Seguran\u00e7a da Informa\u00e7\u00e3o e sua gest\u00e3o? Como se conduzir para\u2026","rel":"","context":"Em &quot;Eventos&quot;","block_context":{"text":"Eventos","link":"https:\/\/mundobibliotecario.com.br\/index.php\/category\/eventos\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1205,"url":"https:\/\/mundobibliotecario.com.br\/index.php\/2010\/04\/14\/revista-editada-na-ufscar-e-indexada-em-base-dados-internacional\/","url_meta":{"origin":3514,"position":5},"title":"Revista editada na UFSCar \u00e9 indexada em base dados internacional","author":"mundobibliotecario","date":"14\/04\/2010","format":false,"excerpt":"A Revista Brasileira de Fisioterapia Brazilian Journal of Physical Therapy (RBF\/BJPT) foi inclu\u00edda na base MEDLINE da National Library of Medicine (NLM). A RBF\/BJPT \u00e9 o primeiro peri\u00f3dico latino-americano da \u00e1rea a atingir esse n\u00edvel de indexa\u00e7\u00e3o e sua inclus\u00e3o na base de dados MEDLINE aumenta a visibilidade de seus\u2026","rel":"","context":"Em &quot;Not\u00edcias&quot;","block_context":{"text":"Not\u00edcias","link":"https:\/\/mundobibliotecario.com.br\/index.php\/category\/noticias\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_likes_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pcbzwa-UG","_links":{"self":[{"href":"https:\/\/mundobibliotecario.com.br\/index.php\/wp-json\/wp\/v2\/posts\/3514","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mundobibliotecario.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mundobibliotecario.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mundobibliotecario.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/mundobibliotecario.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=3514"}],"version-history":[{"count":0,"href":"https:\/\/mundobibliotecario.com.br\/index.php\/wp-json\/wp\/v2\/posts\/3514\/revisions"}],"wp:attachment":[{"href":"https:\/\/mundobibliotecario.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=3514"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mundobibliotecario.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=3514"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mundobibliotecario.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=3514"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}