{"id":4733,"date":"2018-03-27T15:00:43","date_gmt":"2018-03-27T18:00:43","guid":{"rendered":"http:\/\/mundobibliotecario.com.br\/?p=4733"},"modified":"2018-03-27T15:00:43","modified_gmt":"2018-03-27T18:00:43","slug":"novo-curso-de-biblioteconomia-a-distancia-homenageia-prof-a-mariza-russo","status":"publish","type":"post","link":"https:\/\/mundobibliotecario.com.br\/index.php\/2018\/03\/27\/novo-curso-de-biblioteconomia-a-distancia-homenageia-prof-a-mariza-russo\/","title":{"rendered":"Novo curso de biblioteconomia a dist\u00e2ncia homenageia prof.\u00aa Mariza Russo"},"content":{"rendered":"<p>Hoje, 23, foi lan\u00e7ado o curso nacional de bacharelado em Biblioteconomia na modalidade a dist\u00e2ncia (BibEAD). Realizada no edif\u00edcio-sede da Coordena\u00e7\u00e3o de Aperfei\u00e7oamento de Pessoal de N\u00edvel Superior (CAPES), em Bras\u00edlia, a cerim\u00f4nia contou com a presen\u00e7a do presidente substituto da CAPES, prof. Geraldo Nunes, do presidente do Conselho Federal de Biblioteconomia, Raimundo de Lima e do coordenador geral de Programas e Cursos em Ensino a Dist\u00e2ncia da CAPES, Luiz Lira.<\/p>\n<figure class=\"multithumb mtCapStyle\"><a title=\"O presidente substituto da CAPES entregou a homenagem p\u00f3stuma (Foto: Hayd\u00e9e Vieira - CCS\/CAPES)\" href=\"http:\/\/capes.gov.br\/images\/stories\/download\/fotos\/23032018-curso-biblioteconomia-0044.jpg\" target=\"_blank\" rel=\"iLoad noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" title=\"O presidente substituto da CAPES entregou a homenagem p\u00f3stuma (Foto: Hayd\u00e9e Vieira - CCS\/CAPES)\" src=\"http:\/\/capes.gov.br\/images\/multithumb_thumbs\/b_600_250_16777215_00_images_stories_download_fotos_23032018-curso-biblioteconomia-0044.jpg\" alt=\"23032018 curso biblioteconomia 0044\" width=\"205\" height=\"250\" \/><\/a><figcaption>O presidente substituto da CAPES entregou a homenagem p\u00f3stuma (Foto: Hayd\u00e9e Vieira &#8211; CCS\/CAPES)<\/figcaption><\/figure>\n<p>No evento, foi homenageada a professora Mariza Russo, da Universidade Federal do Rio de Janeiro (UFRJ), falecida em 2017. Mariza integrou a equipe que elaborou o projeto do curso. A homenagem foi recebida pela professora Ana Maria Ferreira de Carvalho, da UFRJ. \u201cTrabalhei com Mariza por sete anos. Ela era uma profissional exemplar, combativa, querida pelos alunos. Daremos continuidade ao trabalho dela\u201d, pontou Ana Maria.<\/p>\n<p>Resultado de uma parceria entre a CAPES, o Conselho Federal de Biblioteconomia (CFB) e a Universidade Federal do Rio de Janeiro (UFRJ), o curso integra o sistema\u00a0<a href=\"http:\/\/www.capes.gov.br\/uab\">Universidade Aberta do Brasil (UAB)<\/a>. Com a oferta do curso, a CAPES contribui para a universaliza\u00e7\u00e3o das bibliotecas em institui\u00e7\u00f5es de ensino, prevista para ocorrer at\u00e9 2020 pela Lei 12.244\/2010.<\/p>\n<p><strong>UAB<\/strong><br \/>\nCriada em 2005, a\u00a0<a href=\"http:\/\/www.capes.gov.br\/uab\">Universidade Aberta do Brasil<\/a>\u00a0\u00e9 uma rede formada por institui\u00e7\u00f5es p\u00fablicas que oferece cursos de n\u00edvel superior por meio de educa\u00e7\u00e3o a dist\u00e2ncia. A prioridade da UAB \u00e9 ofertar forma\u00e7\u00e3o para pessoal atuante na educa\u00e7\u00e3o b\u00e1sica \u2013 professores, gestores e colaboradores, mas existem ofertas de forma\u00e7\u00e3o para o p\u00fablico em geral. O Sistema UAB \u00e9 coordenado pela Diretoria de Educa\u00e7\u00e3o a Dist\u00e2ncia (DED) da CAPES.<\/p>\n<p><em>(Bras\u00edlia &#8211; CCS\/CAPES)<\/em><br \/>\n<em>A reprodu\u00e7\u00e3o das not\u00edcias \u00e9 autorizada desde que contenha a assinatura &#8220;CCS\/CAPES&#8221;<\/em><\/p>\n<p>CCS\/CAPES<\/p>\n<p>Dispon\u00edvel em: &lt;<a href=\"http:\/\/capes.gov.br\/sala-de-imprensa\/noticias\/8807-novo-curso-de-biblioteconomia-a-distancia-homenageia-prof-mariza-russo\">http:\/\/capes.gov.br\/sala-de-imprensa\/noticias\/8807-novo-curso-de-biblioteconomia-a-distancia-homenageia-prof-mariza-russo<\/a>&gt;. Acesso em: 27 mar. 2018.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hoje, 23, foi lan\u00e7ado o curso nacional de bacharelado em Biblioteconomia na modalidade a dist\u00e2ncia (BibEAD). Realizada no edif\u00edcio-sede da Coordena\u00e7\u00e3o de Aperfei\u00e7oamento de Pessoal de N\u00edvel Superior (CAPES), em Bras\u00edlia, a cerim\u00f4nia contou com a presen\u00e7a do presidente substituto da CAPES, prof. Geraldo Nunes, do presidente do Conselho Federal de Biblioteconomia, Raimundo de Lima &#8230; <a title=\"Novo curso de biblioteconomia a dist\u00e2ncia homenageia prof.\u00aa Mariza Russo\" class=\"read-more\" href=\"https:\/\/mundobibliotecario.com.br\/index.php\/2018\/03\/27\/novo-curso-de-biblioteconomia-a-distancia-homenageia-prof-a-mariza-russo\/\" aria-label=\"Read more about Novo curso de biblioteconomia a dist\u00e2ncia homenageia prof.\u00aa Mariza Russo\">Ler mais<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_mi_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"_jetpack_newsletter_access":"","footnotes":""},"categories":[60],"tags":[834,1394],"class_list":["post-4733","post","type-post","status-publish","format-standard","hentry","category-noticias","tag-biblioteconomia-a-distancia","tag-biblioteconomia-ead"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack-related-posts":[{"id":2530,"url":"https:\/\/mundobibliotecario.com.br\/index.php\/2012\/03\/27\/edital-apoia-projetos-para-desenvolvimento-de-cursos-de-biblioteconomia-na-modalidade-a-distancia\/","url_meta":{"origin":4733,"position":0},"title":"Edital apoia projetos para desenvolvimento de cursos de biblioteconomia na modalidade a dist\u00e2ncia","author":"mundobibliotecario","date":"27\/03\/2012","format":false,"excerpt":"Aos leitores do Mundo Bibliotec\u00e1rio, uma \u00f3tima not\u00edcia: foi dado mais um passo para a cria\u00e7\u00e3o do curso de Biblioteconomia a dist\u00e2ncia! Confiram! *** Publicada por Assessoria de Comunica\u00e7\u00e3o Social da Capes Segunda, 26 de Mar\u00e7o de 2012 12:17 A Coordena\u00e7\u00e3o de Aperfei\u00e7oamento de Pessoal de N\u00edvel Superior (Capes) divulga\u2026","rel":"","context":"Em &quot;Not\u00edcias&quot;","block_context":{"text":"Not\u00edcias","link":"https:\/\/mundobibliotecario.com.br\/index.php\/category\/noticias\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":2746,"url":"https:\/\/mundobibliotecario.com.br\/index.php\/2012\/11\/11\/capes-aprova-curso-de-biblioteconomia-na-modalidade-a-distancia\/","url_meta":{"origin":4733,"position":1},"title":"Capes aprova curso de Biblioteconomia na modalidade \u00e0 dist\u00e2ncia","author":"mundobibliotecario","date":"11\/11\/2012","format":false,"excerpt":"No \u00faltimo dia 29 de outubro, o Conselho Federal de Biblioteconomia (CFB) protagonizou um momento hist\u00f3rico para a Biblioteconomia no Pa\u00eds. A presidente do CFB, N\u00eamora Rodrigues, assinou junto ao Prof. Dr. Jorge Almeida Guimar\u00e3es, presidente da Coordena\u00e7\u00e3o de Aperfei\u00e7oamento de Pessoal de N\u00edvel Superior (CAPES), um acordo de parceria\u2026","rel":"","context":"Em &quot;Not\u00edcias&quot;","block_context":{"text":"Not\u00edcias","link":"https:\/\/mundobibliotecario.com.br\/index.php\/category\/noticias\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":4731,"url":"https:\/\/mundobibliotecario.com.br\/index.php\/2018\/03\/22\/lancamento-oficial-do-bacharelado-em-biblioteconomia-a-distancia\/","url_meta":{"origin":4733,"position":2},"title":"Lan\u00e7amento oficial do Bacharelado em Biblioteconomia a dist\u00e2ncia","author":"mundobibliotecario","date":"22\/03\/2018","format":false,"excerpt":"Acontecer\u00e1 amanh\u00e3, 23 de mar\u00e7o, o lan\u00e7amento oficial do Bacharelado em Biblioteconomia, modalidade \u00e0 dist\u00e2ncia, da Capes com a Universidade Aberta do Brasil. O evento ser\u00e1 no Audit\u00f3rio Anisio Teixeira, sede da Capes, das 16h \u00e0s 19h, podendo ser acompanhado ao vivo pelo YouTube. O edital 05\/2018 torna p\u00fablico a\u2026","rel":"","context":"Em &quot;Not\u00edcias&quot;","block_context":{"text":"Not\u00edcias","link":"https:\/\/mundobibliotecario.com.br\/index.php\/category\/noticias\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":2257,"url":"https:\/\/mundobibliotecario.com.br\/index.php\/2011\/10\/06\/uab-tera-comissao-tecnica-de-biblioteconomia\/","url_meta":{"origin":4733,"position":3},"title":"UAB ter\u00e1 comiss\u00e3o t\u00e9cnica de biblioteconomia","author":"mundobibliotecario","date":"06\/10\/2011","format":false,"excerpt":"Publicada por Assessoria de Imprensa da Capes Sexta, 11 de Junho de 2010 16:06 O Sistema Universidade Aberta do Brasil (UAB) ter\u00e1 uma Comiss\u00e3o T\u00e9cnica de Biblioteconomia para o acompanhamento e avalia\u00e7\u00e3o das a\u00e7\u00f5es de implanta\u00e7\u00e3o do curso de bacharelado a dist\u00e2ncia na \u00e1rea. O grupo foi institu\u00eddo pela Portaria\u2026","rel":"","context":"Em &quot;Not\u00edcias&quot;","block_context":{"text":"Not\u00edcias","link":"https:\/\/mundobibliotecario.com.br\/index.php\/category\/noticias\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":3017,"url":"https:\/\/mundobibliotecario.com.br\/index.php\/2013\/03\/16\/bacharelado-em-biblioteconomia-a-distancia\/","url_meta":{"origin":4733,"position":4},"title":"Bacharelado em Biblioteconomia a Dist\u00e2ncia","author":"mundobibliotecario","date":"16\/03\/2013","format":false,"excerpt":"Segundo a\u00a0Coordenadoria de Aperfei\u00e7oamento de Pessoal de N\u00edvel Superior (CAPEs), o curso de Bacharelado em Biblioteconomia a Dist\u00e2ncia esta sendo desenvolvido pela\u00a0Universidade Federal do Rio de Janeiro (UFRJ)\u00a0em parceria com\u00a0Conselho Federal de Biblioteconomia (CFB)\u00a0e est\u00e1 previsto para ser ofertado, a partir do segundo semestrede 2014. Esta \u00e9 uma oportunidade para\u2026","rel":"","context":"Em &quot;Not\u00edcias&quot;","block_context":{"text":"Not\u00edcias","link":"https:\/\/mundobibliotecario.com.br\/index.php\/category\/noticias\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":3568,"url":"https:\/\/mundobibliotecario.com.br\/index.php\/2014\/08\/30\/projeto-pedagogico-do-curso-de-biblioteconomia-ead\/","url_meta":{"origin":4733,"position":5},"title":"Projeto pedag\u00f3gico do curso de Biblioteconomia EaD","author":"mundobibliotecario","date":"30\/08\/2014","format":false,"excerpt":"Segue mensagem divulgada pela Prof\u00aa Daniela Spudeit no Facebook sobre o projeto pedag\u00f3gico do curso de Biblioteconomia a dist\u00e2ncia. *** Ol\u00e1, agora que est\u00e1 dispon\u00edvel ao p\u00fablico, divulgo com muito prazer o projeto pedag\u00f3gico do curso de gradua\u00e7\u00e3o em Biblioteconomia na modalidade a dist\u00e2ncia que est\u00e1 sendo organizado pela CAPES\/CFB\/UFRJ\u2026","rel":"","context":"Em &quot;Not\u00edcias&quot;","block_context":{"text":"Not\u00edcias","link":"https:\/\/mundobibliotecario.com.br\/index.php\/category\/noticias\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_likes_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pcbzwa-1el","_links":{"self":[{"href":"https:\/\/mundobibliotecario.com.br\/index.php\/wp-json\/wp\/v2\/posts\/4733","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mundobibliotecario.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mundobibliotecario.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mundobibliotecario.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/mundobibliotecario.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=4733"}],"version-history":[{"count":0,"href":"https:\/\/mundobibliotecario.com.br\/index.php\/wp-json\/wp\/v2\/posts\/4733\/revisions"}],"wp:attachment":[{"href":"https:\/\/mundobibliotecario.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=4733"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mundobibliotecario.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=4733"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mundobibliotecario.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=4733"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}