{"id":4936,"date":"2015-12-24T20:00:45","date_gmt":"2015-12-24T23:00:45","guid":{"rendered":"http:\/\/mundobibliotecario.com.br\/?p=4091"},"modified":"2015-12-24T20:00:45","modified_gmt":"2015-12-24T23:00:45","slug":"altmetria-aplicada-como-as-editoras-academicas-servicos-de-publicacao-academicos-e-repositorios-institucionais-podem-se-beneficiar","status":"publish","type":"post","link":"https:\/\/mundobibliotecario.com.br\/index.php\/2015\/12\/24\/altmetria-aplicada-como-as-editoras-academicas-servicos-de-publicacao-academicos-e-repositorios-institucionais-podem-se-beneficiar\/","title":{"rendered":"Altmetria aplicada: como as editoras acad\u00eamicas, servi\u00e7os de publica\u00e7\u00e3o acad\u00eamicos e reposit\u00f3rios institucionais podem se beneficiar"},"content":{"rendered":"<p>Institui\u00e7\u00f5es acad\u00eamicas est\u00e3o crescentemente procurando maneiras de demonstrar o valor e a amplitude de sua atividade editorial. <strong><a href=\"http:\/\/blogs.lse.ac.uk\/impactofsocialsciences\/2015\/11\/09\/altmetrics-university-press-publishing-services-institutional-repository\/#author\">Danielle Padula<\/a><\/strong><em>\u00a0<\/em>e<em>\u00a0<\/em><strong><a href=\"http:\/\/blogs.lse.ac.uk\/impactofsocialsciences\/2015\/11\/09\/altmetrics-university-press-publishing-services-institutional-repository\/#author\">Catherine Williams<\/a><\/strong> est\u00e3o olhando como uma universidade, a Universidade de Michigan, incorporou os dados de altmetria como um servi\u00e7o para o autor para ajudar seus colegas acad\u00eamicos a articular um sucesso institucional amplo.<\/p>\n<p>***<\/p>\n<p>Este breve relato de caso sobre a aplica\u00e7\u00e3o da altmetria, <a href=\"http:\/\/blogs.lse.ac.uk\/impactofsocialsciences\/2015\/11\/09\/altmetrics-university-press-publishing-services-institutional-repository\/\">Applied Altmetrics: How university presses, academic publishing services and institutional repositories benefit<\/a>, est\u00e1 dispon\u00edvel em ingl\u00eas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Institui\u00e7\u00f5es acad\u00eamicas est\u00e3o crescentemente procurando maneiras de demonstrar o valor e a amplitude de sua atividade editorial. Danielle Padula\u00a0e\u00a0Catherine Williams est\u00e3o olhando como uma universidade, a Universidade de Michigan, incorporou os dados de altmetria como um servi\u00e7o para o autor para ajudar seus colegas acad\u00eamicos a articular um sucesso institucional amplo. *** Este breve relato &#8230; <a title=\"Altmetria aplicada: como as editoras acad\u00eamicas, servi\u00e7os de publica\u00e7\u00e3o acad\u00eamicos e reposit\u00f3rios institucionais podem se beneficiar\" class=\"read-more\" href=\"https:\/\/mundobibliotecario.com.br\/index.php\/2015\/12\/24\/altmetria-aplicada-como-as-editoras-academicas-servicos-de-publicacao-academicos-e-repositorios-institucionais-podem-se-beneficiar\/\" aria-label=\"Read more about Altmetria aplicada: como as editoras acad\u00eamicas, servi\u00e7os de publica\u00e7\u00e3o acad\u00eamicos e reposit\u00f3rios institucionais podem se beneficiar\">Ler mais<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_mi_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"_jetpack_newsletter_access":"","footnotes":""},"categories":[60],"tags":[1339],"class_list":["post-4936","post","type-post","status-publish","format-standard","hentry","category-noticias","tag-altmetria"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack-related-posts":[{"id":10313,"url":"https:\/\/mundobibliotecario.com.br\/index.php\/2023\/05\/10\/tese-o-escritorio-de-comunicacao-cientifica-como-perspectiva-de-atuacao-para-bibliotecas-universitarias-brasileiras\/","url_meta":{"origin":4936,"position":0},"title":"Tese &#8220;O escrit\u00f3rio de comunica\u00e7\u00e3o cient\u00edfica como perspectiva de atua\u00e7\u00e3o para bibliotecas universit\u00e1rias brasileiras&#8221;","author":"mundobibliotecario","date":"10\/05\/2023","format":false,"excerpt":"Informo que minha tese, intitulada \"O escrit\u00f3rio de comunica\u00e7\u00e3o cient\u00edfica como perspectiva de atua\u00e7\u00e3o para bibliotecas universit\u00e1rias brasileiras\" e orientada pelo Prof. Dr. Jos\u00e9 Augusto Chaves Guimar\u00e3es, est\u00e1 dispon\u00edvel para leitura e download no Reposit\u00f3rio Institucional da UNESP no link https:\/\/repositorio.unesp.br\/handle\/11449\/243319. Fonte: Canva Segue o resumo: As mudan\u00e7as ocorridas na\u2026","rel":"","context":"Em &quot;Not\u00edcias&quot;","block_context":{"text":"Not\u00edcias","link":"https:\/\/mundobibliotecario.com.br\/index.php\/category\/noticias\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/mundobibliotecario.com.br\/wp-content\/uploads\/2023\/05\/tese-1.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":7891,"url":"https:\/\/mundobibliotecario.com.br\/index.php\/2020\/10\/20\/ranking-de-repositorios-coloca-sistema-de-bibliotecas-da-fgv-no-top-5-brasileiro\/","url_meta":{"origin":4936,"position":1},"title":"Ranking de reposit\u00f3rios coloca Sistema de Bibliotecas da FGV no top 5 brasileiro","author":"mundobibliotecario","date":"20\/10\/2020","format":false,"excerpt":"O objetivo do Ranking \u00e9 apoiar as iniciativas de Acesso Aberto e, consequentemente, o acesso gratuito \u00e0s publica\u00e7\u00f5es cient\u00edficas em formato eletr\u00f4nico e a outros materiais acad\u00eamicos. O ranking avalia crit\u00e9rios como a visibilidade global e o impacto dos reposit\u00f3rios cient\u00edficos. \u00a0 O Sistema de Bibliotecas da FGV est\u00e1 no\u2026","rel":"","context":"Em &quot;Not\u00edcias&quot;","block_context":{"text":"Not\u00edcias","link":"https:\/\/mundobibliotecario.com.br\/index.php\/category\/noticias\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":4820,"url":"https:\/\/mundobibliotecario.com.br\/index.php\/2018\/07\/09\/rotas-alternativas-para-artigos-academicos-e-resultados-de-pesquisa\/","url_meta":{"origin":4936,"position":2},"title":"Rotas alternativas para artigos acad\u00eamicos e resultados de pesquisa","author":"mundobibliotecario","date":"09\/07\/2018","format":false,"excerpt":"Muitos artigos acad\u00eamicos e revisados por pares podem ser lidos hoje em dia na web. V\u00e1rios servi\u00e7os e arquivos gratuitos desenvolveram ferramentas e servi\u00e7os que ajudam os usu\u00e1rios a descobrir resultados de pesquisa de maneira f\u00e1cil e simples: por meio da instala\u00e7\u00e3o de uma extens\u00e3o ou plug-in do navegador; usando\u2026","rel":"","context":"Em &quot;Not\u00edcias&quot;","block_context":{"text":"Not\u00edcias","link":"https:\/\/mundobibliotecario.com.br\/index.php\/category\/noticias\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/mundobibliotecario.com.br\/wp-content\/uploads\/2018\/07\/800px-open_access_plos-svg.png?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":10050,"url":"https:\/\/mundobibliotecario.com.br\/index.php\/2022\/07\/25\/criacao-da-agencia-de-bibliotecas-e-colecoes-digitais-da-universidade-de-sao-paulo-abcd-usp\/","url_meta":{"origin":4936,"position":3},"title":"Cria\u00e7\u00e3o da Ag\u00eancia de Bibliotecas e Cole\u00e7\u00f5es Digitais da Universidade de S\u00e3o Paulo (ABCD-USP)","author":"mundobibliotecario","date":"25\/07\/2022","format":false,"excerpt":"D.O.E.: 01\/07\/2022 RESOLU\u00c7\u00c3O N\u00ba 8269, DE 30 DE JUNHO DE 2022 (Revoga a Resolu\u00e7\u00e3o\u00a07791\/2019) Disp\u00f5e sobre a cria\u00e7\u00e3o da Ag\u00eancia de Bibliotecas e Cole\u00e7\u00f5es Digitais (ABCD) e d\u00e1 outras provid\u00eancias. O Reitor da Universidade de S\u00e3o Paulo, usando de suas atribui\u00e7\u00f5es legais, com fundamento no\u00a0art 42, IX, do Estatuto, tendo\u2026","rel":"","context":"Em &quot;Not\u00edcias&quot;","block_context":{"text":"Not\u00edcias","link":"https:\/\/mundobibliotecario.com.br\/index.php\/category\/noticias\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.aguia.usp.br\/wp-content\/uploads\/2022\/07\/abcd-300x250.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":5323,"url":"https:\/\/mundobibliotecario.com.br\/index.php\/2019\/10\/01\/presidente-da-agencia-usp-de-gestao-da-informacao-academica-visita-as-instalacoes-do-sdo\/","url_meta":{"origin":4936,"position":4},"title":"Presidente da Ag\u00eancia USP de Gest\u00e3o da Informa\u00e7\u00e3o Acad\u00eamica visita as instala\u00e7\u00f5es do SDO","author":"mundobibliotecario","date":"01\/10\/2019","format":false,"excerpt":"No final da tarde de ter\u00e7a-feira, 24 de setembro de 2019, a FOUSP recebeu a visita do Presidente da Ag\u00eancia USP de Gest\u00e3o da Informa\u00e7\u00e3o Acad\u00eamica, Prof. Dr. Jackson Cioni Bittencourt. A fim de conhecer a estrutura do local, o Presidente foi recebido pelo Diretor Prof. Dr. Rodney Garcia Rocha,\u2026","rel":"","context":"Em &quot;Not\u00edcias&quot;","block_context":{"text":"Not\u00edcias","link":"https:\/\/mundobibliotecario.com.br\/index.php\/category\/noticias\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/mundobibliotecario.com.br\/wp-content\/uploads\/2019\/09\/foto.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":1883,"url":"https:\/\/mundobibliotecario.com.br\/index.php\/2011\/03\/16\/scielo-no-topo-de-ranking-mundial\/","url_meta":{"origin":4936,"position":5},"title":"SciELO no topo de ranking mundial","author":"mundobibliotecario","date":"16\/03\/2011","format":false,"excerpt":"Especiais 15\/3\/2011 Por Fabr\u00edcio Marques Pesquisa FAPESP \u2013 A biblioteca eletr\u00f4nica SciELO Brasil foi classificada em 1\u00ba lugar no ranking mundial de portais de acesso aberto Webometrics, divulgado pelo laborat\u00f3rio Cybermetrics, grupo de pesquisa vinculado ao Conselho Superior de Pesquisas Cient\u00edficas da Espanha. Curiosamente, a SciELO Brasil n\u00e3o estava em\u2026","rel":"","context":"Em &quot;Not\u00edcias&quot;","block_context":{"text":"Not\u00edcias","link":"https:\/\/mundobibliotecario.com.br\/index.php\/category\/noticias\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_likes_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pcbzwa-1hC","_links":{"self":[{"href":"https:\/\/mundobibliotecario.com.br\/index.php\/wp-json\/wp\/v2\/posts\/4936","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mundobibliotecario.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mundobibliotecario.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mundobibliotecario.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/mundobibliotecario.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=4936"}],"version-history":[{"count":0,"href":"https:\/\/mundobibliotecario.com.br\/index.php\/wp-json\/wp\/v2\/posts\/4936\/revisions"}],"wp:attachment":[{"href":"https:\/\/mundobibliotecario.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=4936"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mundobibliotecario.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=4936"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mundobibliotecario.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=4936"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}