{"id":544,"date":"2009-04-13T08:27:35","date_gmt":"2009-04-13T11:27:35","guid":{"rendered":"http:\/\/mundobibliotecario.wordpress.com\/?p=544"},"modified":"2020-07-21T23:25:42","modified_gmt":"2020-07-22T02:25:42","slug":"empresas-do-ramo-dos-livros-sentem-peso-da-concorrencia","status":"publish","type":"post","link":"https:\/\/mundobibliotecario.com.br\/index.php\/2009\/04\/13\/empresas-do-ramo-dos-livros-sentem-peso-da-concorrencia\/","title":{"rendered":"Empresas do ramo dos livros sentem peso da concorr\u00eancia"},"content":{"rendered":"<p>Nilbberth Silva \/ Ag\u00eancia USP<\/p>\n<p>O mercado do livro no Pa\u00eds enfrenta dificuldades cr\u00f4nicas pr\u00f3prias da \u00e1rea e excesso de competi\u00e7\u00e3o. As editoras de sucesso s\u00e3o aquelas que t\u00eam vantagens, como a vincula\u00e7\u00e3o a empresas maiores, multinacionais estrangeiras, organiza\u00e7\u00f5es religiosas ou sistemas de ensino. Os leitores aprendem a ler por imposi\u00e7\u00e3o e, para muitos, a leitura \u00e9 um h\u00e1bito dif\u00edcil e n\u00e3o prazeroso. Essas s\u00e3o algumas conclus\u00f5es de uma tese de doutorado defendida em novembro de 2008 na Escola de Comunica\u00e7\u00f5es e Artes (ECA) da USP pelo editor Jos\u00e9 Rosa.<\/p>\n<p>Com cerca de 20 mil funcion\u00e1rios e movimentando apenas R$ 3 bilh\u00f5es, a ind\u00fastria editorial tem uma import\u00e2ncia econ\u00f4mica pequena no Brasil.<\/p>\n<p>Fabricantes de livros t\u00eam problemas com falta de tempo das pessoas para a leitura, dificuldade de achar o livro &#8220;certo&#8221; em meio \u00e0 grande oferta, escassez de bibliotecas e altos pre\u00e7os dos livros. Al\u00e9m disso, segundo o Instituto Brasileiro de Alfabetiza\u00e7\u00e3o Funcional (INAF) apenas 26% dos brasileiros de 15 a 64 anos mostraram capacidade de ler, entender e resumir textos longos e encontrar informa\u00e7\u00f5es neles \u2014 alfabetiza\u00e7\u00e3o plena.<\/p>\n<p>Al\u00e9m disso, um pequeno n\u00famero de editoras domina uma parcela grande do mercado. &#8220;O Brasil tem, aproximadamente, 600 editoras. Dessas, 30 provavelmente det\u00e9m 70% do faturamento da ind\u00fastria do livro&#8221;, explica Rosa.<\/p>\n<p>Editoras de sucesso geralmente est\u00e3o vinculadas a grupos de m\u00eddia, a editoras globalizadas, redes comerciais, sistemas de ensino, ou a outras empresas, universidades e grupos religiosos. As editoras mais expostas \u00e0 dificuldades do mercado s\u00e3o as pequenas nacionais e independentes. Essas t\u00eam menos poder de negocia\u00e7\u00e3o, mas, como t\u00eam custos menores, acomodam-se melhor \u00e0s mudan\u00e7as do mercado editorial e a insucessos de seus lan\u00e7amentos.<\/p>\n<p>Editoras menores sobrevivem vendendo poucos livros, em geral e especializados em algum segmento. &#8220;O custo de montar uma editora \u00e9 baixo, por isso \u00e9 facil entrar no mercado. Mas \u00e9 dif\u00edcil vender livros e permanecer&#8221;, conta o pesquisador. Mesmo assim, no Brasil a quantidade de t\u00edtulos aumenta \u2014 s\u00e3o lan\u00e7ados por volta de 1500 por m\u00eas. &#8220;Esses t\u00edtulos t\u00eam menores tiragens. As livrarias n\u00e3o d\u00e3o vaz\u00e3o a tudo&#8221;, explica Rosa.<\/p>\n<p>Para escrever a tese, Rosa partiu de sua experi\u00eancia profissional de 20 anos, analisou dados estat\u00edsticos e pequisas internacionais, entrevistou donos de livrarias e administradores bem sucedidos de editoras. Por fim, conversou com dez pessoas que l\u00eaem mais de 20 livros por ano e 12 que n\u00e3o tinham o h\u00e1bito de ler, mesmo tendo condi\u00e7\u00f5es para isso. A tese foi orientada pelo professor Mitsuru Yanaze.<\/p>\n<p>Comportamento dos leitores<br \/>\nJos\u00e9 Rosa obteve informa\u00e7\u00f5es iniciais sobre o comportamento do leitor que podem dar base a outros pesquisadores, para maior aprofundamento. A tese mostra que leitores ass\u00edduos aprenderam a ler cedo e t\u00eam potencial para gastar tempo e dinheiro com o livro. Eles n\u00e3o prezam, necessariamente, pela qualidade e come\u00e7aram a ler em raz\u00e3o de alguma necessidade.<\/p>\n<p>Para a maioria das pessoas, ler \u00e9 um exerc\u00edcio dif\u00edcil e n\u00e3o-prazeroso. Ele geralmente surge por auto-imposi\u00e7\u00e3o, imposi\u00e7\u00e3o da escola, igreja, trabalho, ou por descoberta de livros que motivem muito o leitor. Depois, a leitura torna-se cada vez mais prazerosa. O pesquisador tamb\u00e9m percebeu que o livro \u00e9 universalmente valorizado, at\u00e9 por quem nunca leu um.<\/p>\n<p>Para o pesquisador, o futuro da ind\u00fastria do livro \u00e9 incerto. \u201cO estilo de texto do livro deve sobreviver, mas em formatos digitais\u201d, explica. \u201cO livro digital \u00e9 mais ecol\u00f3gico, com custos de produ\u00e7\u00e3o e distribui\u00e7\u00e3o menores\u201d. Rosa tamb\u00e9m considera poss\u00edvel que o livro perca a import\u00e2ncia que teve no passado: &#8221; Com a internet a pessoa acessa a informa\u00e7\u00e3o e cultura sem passar pelo livro impresso&#8221;, explica.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nilbberth Silva \/ Ag\u00eancia USP O mercado do livro no Pa\u00eds enfrenta dificuldades cr\u00f4nicas pr\u00f3prias da \u00e1rea e excesso de competi\u00e7\u00e3o. As editoras de sucesso s\u00e3o aquelas que t\u00eam vantagens, como a vincula\u00e7\u00e3o a empresas maiores, multinacionais estrangeiras, organiza\u00e7\u00f5es religiosas ou sistemas de ensino. Os leitores aprendem a ler por imposi\u00e7\u00e3o e, para muitos, a &#8230; <a title=\"Empresas do ramo dos livros sentem peso da concorr\u00eancia\" class=\"read-more\" href=\"https:\/\/mundobibliotecario.com.br\/index.php\/2009\/04\/13\/empresas-do-ramo-dos-livros-sentem-peso-da-concorrencia\/\" aria-label=\"Read more about Empresas do ramo dos livros sentem peso da concorr\u00eancia\">Ler mais<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_mi_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"_jetpack_newsletter_access":"","footnotes":""},"categories":[60],"tags":[325,353,354,8,9,355],"class_list":["post-544","post","type-post","status-publish","format-standard","hentry","category-noticias","tag-eca-usp","tag-editora","tag-instituto-brasileiro-de-alfabetizacao-funcional-inaf","tag-leitura","tag-livro","tag-livro-digital"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack-related-posts":[{"id":4969,"url":"https:\/\/mundobibliotecario.com.br\/index.php\/2018\/08\/07\/especialistas-discutem-a-importancia-da-leitura-na-sociedade\/","url_meta":{"origin":544,"position":0},"title":"Especialistas discutem a import\u00e2ncia da leitura na sociedade","author":"mundobibliotecario","date":"07\/08\/2018","format":false,"excerpt":"Livro e leitura no Brasil foi o tema do programa \u201cDi\u00e1logos na USP\u201d, da R\u00e1dio USP, nesta sexta-feira, dia 3 O programa\u00a0Di\u00e1logos na USP \u2013 Os Temas da Atualidade, transmitido ao vivo pela R\u00e1dio USP (93,7 MHz) no dia 3 de agosto de 2018, abordou a import\u00e2ncia da Bienal Internacional\u2026","rel":"","context":"Em &quot;Not\u00edcias&quot;","block_context":{"text":"Not\u00edcias","link":"https:\/\/mundobibliotecario.com.br\/index.php\/category\/noticias\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/jornal.usp.br\/wp-content\/uploads\/2018\/08\/20180803_00_bienal_livro_sao_paulo.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":4968,"url":"https:\/\/mundobibliotecario.com.br\/index.php\/2018\/08\/06\/livros-de-youtubers-sao-um-fenomeno-no-mercado-editorial\/","url_meta":{"origin":544,"position":1},"title":"Livros de youtubers s\u00e3o um fen\u00f4meno no mercado editorial","author":"mundobibliotecario","date":"06\/08\/2018","format":false,"excerpt":"Diversos youtubers estar\u00e3o na Bienal Internacional do Livro de S\u00e3o Paulo, representando seus trabalhos liter\u00e1rios Por\u00a0Let\u00edcia Tanaka\u00a0- Editorias:\u00a0Atualidades,\u00a0R\u00e1dio USP \u00a0 Biena (sic) do livro \u2013 Foto: Marcos Santos \/ USP Imagens A 25\u00aa Bienal Internacional do Livro de S\u00e3o Paulo\u00a0 que come\u00e7a hoje, dia 3, e vai at\u00e9 o dia\u2026","rel":"","context":"Em &quot;N\u00e3o classificado&quot;","block_context":{"text":"N\u00e3o classificado","link":"https:\/\/mundobibliotecario.com.br\/index.php\/category\/nao-classificado\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":5248,"url":"https:\/\/mundobibliotecario.com.br\/index.php\/2019\/08\/22\/editoras-de-universidades-paulistas-expandem-catalogo-de-publicacoes\/","url_meta":{"origin":544,"position":2},"title":"Editoras de universidades paulistas expandem cat\u00e1logo de publica\u00e7\u00f5es","author":"mundobibliotecario","date":"22\/08\/2019","format":false,"excerpt":"Institui\u00e7\u00f5es ligadas \u00e0 Unicamp, USP e Unesp difundem o conhecimento produzido pelos professores e pesquisadores no Estado Nos \u00faltimos anos, as editoras da Universidade de S\u00e3o Paulo (USP), Universidade Estadual Paulista (Unesp) e Universidade Estadual de Campinas (Unicamp) diversificaram os cat\u00e1logos com t\u00edtulos que abrangem todas as \u00e1reas. Elas t\u00eam\u2026","rel":"","context":"Em &quot;Not\u00edcias&quot;","block_context":{"text":"Not\u00edcias","link":"https:\/\/mundobibliotecario.com.br\/index.php\/category\/noticias\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":4565,"url":"https:\/\/mundobibliotecario.com.br\/index.php\/2017\/08\/16\/historiador-frances-vem-a-usp-para-debate-sobre-o-medo-dos-livros\/","url_meta":{"origin":544,"position":3},"title":"Historiador franc\u00eas vem \u00e0 USP para debate sobre o medo dos livros","author":"mundobibliotecario","date":"16\/08\/2017","format":false,"excerpt":"Em evento no Instituto de Estudos Avan\u00e7ados, Jean-Yves Mollier vai abordar o poder pol\u00edtico da literatura Por\u00a0Diego C. Smirne\u00a0- Editorias:\u00a0Cultura Foto: Marcos Santos \/ USP Imagens H\u00e1 quem considere o advento da escrita como o maior divisor de \u00e1guas da hist\u00f3ria da humanidade. Tomando essa premissa como verdadeira, n\u00e3o \u00e9\u2026","rel":"","context":"Em &quot;Eventos&quot;","block_context":{"text":"Eventos","link":"https:\/\/mundobibliotecario.com.br\/index.php\/category\/eventos\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/jornal.usp.br\/wp-content\/uploads\/20170609_00_livro4.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":3617,"url":"https:\/\/mundobibliotecario.com.br\/index.php\/2014\/10\/23\/encontro-abrainfo-passo-a-passo\/","url_meta":{"origin":544,"position":4},"title":"Encontro &#8220;ABRAINFO: passo a passo&#8221;","author":"mundobibliotecario","date":"23\/10\/2014","format":false,"excerpt":"Problema com a visualiza\u00e7\u00e3o da mensagem? Clique aqui. Prezada(o) Amig(a)o, Em comemora\u00e7\u00e3o ao nosso segundo ano de exist\u00eancia, realizaremos um encontro para promover um balan\u00e7o desse per\u00edodo e das perspectivas que se apresentam para a \u00e1rea de informa\u00e7\u00e3o. Nesta oportunidade, realizaremos tamb\u00e9m uma mesa-redonda para que alguns profissionais, que participaram\u2026","rel":"","context":"Em &quot;Eventos&quot;","block_context":{"text":"Eventos","link":"https:\/\/mundobibliotecario.com.br\/index.php\/category\/eventos\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1469,"url":"https:\/\/mundobibliotecario.com.br\/index.php\/2010\/09\/24\/v-semana-de-biblioteconomia-da-ecausp\/","url_meta":{"origin":544,"position":5},"title":"V Semana de Biblioteconomia da ECA\/USP","author":"mundobibliotecario","date":"24\/09\/2010","format":false,"excerpt":"V Semana de Biblioteconomia da Escola de Comunica\u00e7\u00f5es e Artes (ECA) da Universidade de S\u00e3o Paulo (USP) De 27\/09 a 01\/10 A Semana de Biblioteconomia da Escola de Comunica\u00e7\u00f5es e Artes (ECA) da Universidade de S\u00e3o Paulo (USP) \u00e9 em evento acad\u00eamico que objetiva estimular e promover o esp\u00edrito cr\u00edtico\u2026","rel":"","context":"Em &quot;Eventos&quot;","block_context":{"text":"Eventos","link":"https:\/\/mundobibliotecario.com.br\/index.php\/category\/eventos\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_likes_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pcbzwa-8M","_links":{"self":[{"href":"https:\/\/mundobibliotecario.com.br\/index.php\/wp-json\/wp\/v2\/posts\/544","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mundobibliotecario.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mundobibliotecario.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mundobibliotecario.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/mundobibliotecario.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=544"}],"version-history":[{"count":1,"href":"https:\/\/mundobibliotecario.com.br\/index.php\/wp-json\/wp\/v2\/posts\/544\/revisions"}],"predecessor-version":[{"id":6786,"href":"https:\/\/mundobibliotecario.com.br\/index.php\/wp-json\/wp\/v2\/posts\/544\/revisions\/6786"}],"wp:attachment":[{"href":"https:\/\/mundobibliotecario.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=544"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mundobibliotecario.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=544"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mundobibliotecario.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=544"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}