{"id":5456,"date":"2020-01-13T16:00:00","date_gmt":"2020-01-13T19:00:00","guid":{"rendered":"http:\/\/mundobibliotecario.com.br\/?p=5456"},"modified":"2020-07-18T18:10:35","modified_gmt":"2020-07-18T21:10:35","slug":"conheca-3-ferramentas-gratuitas-para-produzir-conteudo-para-redes-sociais-em-bibliotecas","status":"publish","type":"post","link":"https:\/\/mundobibliotecario.com.br\/index.php\/2020\/01\/13\/conheca-3-ferramentas-gratuitas-para-produzir-conteudo-para-redes-sociais-em-bibliotecas\/","title":{"rendered":"Conhe\u00e7a 3 ferramentas (gratuitas!) para produzir conte\u00fado para redes sociais em bibliotecas"},"content":{"rendered":"\n<p>Recentemente, publiquei um post sobre <a href=\"https:\/\/mundobibliotecario.com.br\/index.php\/tag\/biblioteconomia-a-distancia\/\">como identificar o perfil dos usu\u00e1rios das redes sociais da biblioteca<\/a>. Uma vez que voc\u00ea conhece quem \u00e9 o p\u00fablico, fica mais f\u00e1cil produzir o conte\u00fado, certo?<\/p>\n\n\n\n<p>Mas com o volume de informa\u00e7\u00f5es dispon\u00edvel hoje, \u00e9 imposs\u00edvel fazer esse  trabalho sem utilizar ferramentas para produzir os melhores conte\u00fados. Neste texto, voc\u00ea vai conhecer 3 ferramentas gratuitas que te ajudar\u00e3o a ter ideias de conte\u00fado para o p\u00fablico.<\/p>\n\n\n\n<p>Continue no texto para conhecer essas ferramentas!<\/p>\n\n\n\n<!--more-->\n\n\n\n<h2 class=\"wp-block-heading\">1. Google Trends<\/h2>\n\n\n\n<p>O <a href=\"https:\/\/trends.google.com\/trends\/\">Google Trends<\/a> \u00e9 uma ferramenta gratuita do Google para an\u00e1lise e visualiza\u00e7\u00e3o de tend\u00eancias ao longo do tempo.<\/p>\n\n\n\n<p>O uso \u00e9 muito simples: voc\u00ea apenas digita a palavra-chave na ferramenta e em poucos segundos voc\u00ea visualizar\u00e1 um gr\u00e1fico mostrando o interesse no assunto durante um per\u00edodo.<\/p>\n\n\n\n<p>Ele tamb\u00e9m mostra informa\u00e7\u00f5es de interesse por sub-regi\u00e3o (no caso do Brasil, por Estados), assuntos relacionados (com a indica\u00e7\u00e3o em porcentagem do interesse nesses assuntos) e consultas relacionadas \u00e0 palavra-chave que voc\u00ea pesquisou.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1321\" height=\"600\" src=\"http:\/\/mundobibliotecario.com.br\/wp-content\/uploads\/2020\/01\/image.png?w=1024\" alt=\"\" class=\"wp-image-5460\" srcset=\"https:\/\/mundobibliotecario.com.br\/wp-content\/uploads\/2020\/01\/image.png 1321w, https:\/\/mundobibliotecario.com.br\/wp-content\/uploads\/2020\/01\/image-300x136.png 300w, https:\/\/mundobibliotecario.com.br\/wp-content\/uploads\/2020\/01\/image-1024x465.png 1024w, https:\/\/mundobibliotecario.com.br\/wp-content\/uploads\/2020\/01\/image-768x349.png 768w\" sizes=\"auto, (max-width: 1321px) 100vw, 1321px\" \/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\"> 2. Ubersuggest<\/h2>\n\n\n\n<p>Outra ferramenta gratuita para ter ideias (literalmente!) de conte\u00fado \u00e9 o <a href=\"https:\/\/neilpatel.com\/br\/ubersuggest\/\">Ubersuggest<\/a>.<\/p>\n\n\n\n<p>O diferencial desta ferramenta \u00e9 que al\u00e9m do gr\u00e1fico de interesse no assunto, ela tamb\u00e9m apresenta ideias de palavras-chave com a quantidade de cliques que cada uma delas recebeu.<\/p>\n\n\n\n<p>Essa \u00e9 uma informa\u00e7\u00e3o importante para verificar antes de selecionar uma palavra-chave, pois assim \u00e9 poss\u00edvel ter maiores chances de que o seu p\u00fablico v\u00e1 encontrar o seu conte\u00fado.<\/p>\n\n\n\n<p>O Ubersuggest tamb\u00e9m oferece &#8220;ideias de conte\u00fado&#8221;. Essas &#8220;ideias&#8221; nada mais s\u00e3o do que sites que t\u00eam a palavra-chave pesquisada com a indica\u00e7\u00e3o aproximada de visitas, al\u00e9m da quantidade de cliques recebidos no Facebook e Pinterest.<\/p>\n\n\n\n<p>De quebra, essa ferramenta tamb\u00e9m tem um pequeno gr\u00e1fico (abaixo do principal) que mostra a porcentagem de pessoas, separadas por faixa et\u00e1ria, que mais procuram pelo assunto.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1323\" height=\"601\" src=\"http:\/\/mundobibliotecario.com.br\/wp-content\/uploads\/2020\/01\/image-1.png?w=1024\" alt=\"\" class=\"wp-image-5462\" srcset=\"https:\/\/mundobibliotecario.com.br\/wp-content\/uploads\/2020\/01\/image-1.png 1323w, https:\/\/mundobibliotecario.com.br\/wp-content\/uploads\/2020\/01\/image-1-300x136.png 300w, https:\/\/mundobibliotecario.com.br\/wp-content\/uploads\/2020\/01\/image-1-1024x465.png 1024w, https:\/\/mundobibliotecario.com.br\/wp-content\/uploads\/2020\/01\/image-1-768x349.png 768w\" sizes=\"auto, (max-width: 1323px) 100vw, 1323px\" \/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">3. Answer The Public<\/h2>\n\n\n\n<p>O <a href=\"https:\/\/answerthepublic.com\/\">Answer The Public<\/a> apresenta os resultados de uma forma gr\u00e1fica, mas n\u00e3o convencional. O visual \u00e9 bastante interessante porque apresenta a palavra-chave pesquisada em t\u00f3picos, conforme mostra a figura abaixo.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1348\" height=\"618\" src=\"http:\/\/mundobibliotecario.com.br\/wp-content\/uploads\/2020\/01\/image-2.png?w=1024\" alt=\"\" class=\"wp-image-5464\" srcset=\"https:\/\/mundobibliotecario.com.br\/wp-content\/uploads\/2020\/01\/image-2.png 1348w, https:\/\/mundobibliotecario.com.br\/wp-content\/uploads\/2020\/01\/image-2-300x138.png 300w, https:\/\/mundobibliotecario.com.br\/wp-content\/uploads\/2020\/01\/image-2-1024x469.png 1024w, https:\/\/mundobibliotecario.com.br\/wp-content\/uploads\/2020\/01\/image-2-768x352.png 768w\" sizes=\"auto, (max-width: 1348px) 100vw, 1348px\" \/><\/figure>\n\n\n\n<p>Os resultados s\u00e3o divididos em:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Quest\u00f5es<\/li><li>Preposi\u00e7\u00f5es<\/li><li>Compara\u00e7\u00f5es<\/li><li>Ordem alfab\u00e9tica<\/li><li>Relacionados<\/li><\/ul>\n\n\n\n<h2 class=\"wp-block-heading\">DICA B\u00d4NUS!<\/h2>\n\n\n\n<p>O Answer The Public n\u00e3o quantifica o volume de buscas para as palavras-chaves.<\/p>\n\n\n\n<p>Para verificar o volume, selecione as palavras-chave mais interessantes para o seu conte\u00fado e &#8220;d\u00ea um Google&#8221; nelas. No exemplo abaixo, a palavra-chave &#8220;scielo busca avan\u00e7ada&#8221; tem aproximadamente 319.000 resultados.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"988\" height=\"513\" src=\"http:\/\/mundobibliotecario.com.br\/wp-content\/uploads\/2020\/01\/image-3.png?w=988\" alt=\"\" class=\"wp-image-5466\" srcset=\"https:\/\/mundobibliotecario.com.br\/wp-content\/uploads\/2020\/01\/image-3.png 988w, https:\/\/mundobibliotecario.com.br\/wp-content\/uploads\/2020\/01\/image-3-300x156.png 300w, https:\/\/mundobibliotecario.com.br\/wp-content\/uploads\/2020\/01\/image-3-768x399.png 768w\" sizes=\"auto, (max-width: 988px) 100vw, 988px\" \/><\/figure>\n\n\n\n<p>Gostou das dicas? Usa alguma outra ferramenta?<\/p>\n\n\n\n<p>Deixe um coment\u00e1rio!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Recentemente, publiquei um post sobre como identificar o perfil dos usu\u00e1rios das redes sociais da biblioteca. Uma vez que voc\u00ea conhece quem \u00e9 o p\u00fablico, fica mais f\u00e1cil produzir o conte\u00fado, certo? Mas com o volume de informa\u00e7\u00f5es dispon\u00edvel hoje, \u00e9 imposs\u00edvel fazer esse trabalho sem utilizar ferramentas para produzir os melhores conte\u00fados. Neste texto, &#8230; <a title=\"Conhe\u00e7a 3 ferramentas (gratuitas!) para produzir conte\u00fado para redes sociais em bibliotecas\" class=\"read-more\" href=\"https:\/\/mundobibliotecario.com.br\/index.php\/2020\/01\/13\/conheca-3-ferramentas-gratuitas-para-produzir-conteudo-para-redes-sociais-em-bibliotecas\/\" aria-label=\"Read more about Conhe\u00e7a 3 ferramentas (gratuitas!) para produzir conte\u00fado para redes sociais em bibliotecas\">Ler mais<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_mi_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"_jetpack_newsletter_access":"","footnotes":""},"categories":[60],"tags":[],"class_list":["post-5456","post","type-post","status-publish","format-standard","hentry","category-noticias"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack-related-posts":[{"id":4787,"url":"https:\/\/mundobibliotecario.com.br\/index.php\/2018\/06\/04\/como-usar-o-botao-do-google-academico\/","url_meta":{"origin":5456,"position":0},"title":"Como usar o bot\u00e3o do Google Acad\u00eamico","author":"mundobibliotecario","date":"04\/06\/2018","format":false,"excerpt":"O Google Acad\u00eamico \u00e9 uma das ferramentas mais utilizadas hoje para se fazer pesquisas. Sua principal vantagem \u00e9 ser uma ferramenta gratuita, diferentemente de bases de dados assinadas pelas bibliotecas das institui\u00e7\u00f5es de ensino superior. Por outro lado, nem sempre \u00e9 poss\u00edvel se certificar sobre a origem do conte\u00fado. N\u00e3o\u2026","rel":"","context":"Em &quot;Voc\u00ea sabia?&quot;","block_context":{"text":"Voc\u00ea sabia?","link":"https:\/\/mundobibliotecario.com.br\/index.php\/category\/voce-sabia\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":3535,"url":"https:\/\/mundobibliotecario.com.br\/index.php\/2014\/07\/13\/como-checar-o-conteudo-divulgado-em-redes-sociais\/","url_meta":{"origin":5456,"position":1},"title":"Como checar o conte\u00fado divulgado em redes sociais","author":"mundobibliotecario","date":"13\/07\/2014","format":false,"excerpt":"Os bibliotec\u00e1rios costumam falar que trabalham com informa\u00e7\u00e3o, conhecimento e, mais recentemente, com conte\u00fado. Ent\u00e3o porque n\u00e3o dar um conferida neste manual? Ou, melhor ainda, porque n\u00e3o pensarmos juntos em elaborar um manual pr\u00f3prio para nossa profiss\u00e3o? Afinal, como os jornalistas, devemos estar atento \u00e0s fontes de informa\u00e7\u00e3o e, claro,\u2026","rel":"","context":"Em &quot;Not\u00edcias&quot;","block_context":{"text":"Not\u00edcias","link":"https:\/\/mundobibliotecario.com.br\/index.php\/category\/noticias\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":9744,"url":"https:\/\/mundobibliotecario.com.br\/index.php\/2022\/01\/17\/guias-de-melhores-praticas-em-redes-sociais-para-bibliotecas-para-2022\/","url_meta":{"origin":5456,"position":2},"title":"Guias de melhores pr\u00e1ticas em redes sociais para bibliotecas para 2022","author":"mundobibliotecario","date":"17\/01\/2022","format":false,"excerpt":"O site Super Library Marketing preparou uma s\u00e9rie de guias de melhores pr\u00e1ticas para redes sociais para bibliotecas em 2022. Est\u00e3o dispon\u00edveis guias para as seguintes redes: Facebook Instagram TikTok YouTube Pinterest LinkedIn Os guias apresentam algumas estat\u00edsticas de uso dessas redes, al\u00e9m de dicas sobre o melhor tipo de\u2026","rel":"","context":"Em &quot;Not\u00edcias&quot;","block_context":{"text":"Not\u00edcias","link":"https:\/\/mundobibliotecario.com.br\/index.php\/category\/noticias\/"},"img":{"alt_text":"redes sociais","src":"https:\/\/i0.wp.com\/mundobibliotecario.com.br\/wp-content\/uploads\/2022\/01\/28188286432_3353c1c7ed_w.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":5390,"url":"https:\/\/mundobibliotecario.com.br\/index.php\/2019\/12\/30\/estudo-de-usuarios-na-web-conheca-duas-tecnicas-que-o-curso-de-biblioteconomia-nao-ensina\/","url_meta":{"origin":5456,"position":3},"title":"Estudo de usu\u00e1rios na web: conhe\u00e7a duas t\u00e9cnicas que o curso de Biblioteconomia n\u00e3o ensina","author":"mundobibliotecario","date":"30\/12\/2019","format":false,"excerpt":"Se voc\u00ea \u00e9 o respons\u00e1vel pelo gerenciamento das redes sociais da biblioteca, provavelmente j\u00e1 deve ter visto gr\u00e1ficos e n\u00fameros fornecidas pelas pr\u00f3prias redes. Eles variam desde a quantidade de compartilhamentos, curtidas, informa\u00e7\u00f5es demogr\u00e1ficas e outras. \u00c9 preciso ir al\u00e9m desses dados e entender como eles podem ser aplicados na\u2026","rel":"","context":"Em &quot;Not\u00edcias&quot;","block_context":{"text":"Not\u00edcias","link":"https:\/\/mundobibliotecario.com.br\/index.php\/category\/noticias\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/mundobibliotecario.com.br\/wp-content\/uploads\/2020\/01\/instagram.png?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":10181,"url":"https:\/\/mundobibliotecario.com.br\/index.php\/2022\/11\/14\/google-vs-biblioteca-qual-e-o-melhor-lugar-para-pesquisar\/","url_meta":{"origin":5456,"position":4},"title":"Google vs. Biblioteca: qual \u00e9 o melhor lugar para pesquisar?","author":"mundobibliotecario","date":"14\/11\/2022","format":false,"excerpt":"Quando se trata de pesquisar na internet, h\u00e1 duas op\u00e7\u00f5es principais: o Google e as bibliotecas. Qual \u00e9 o melhor lugar para pesquisar? Isso depende do que voc\u00ea est\u00e1 procurando. Se voc\u00ea est\u00e1 procurando um livro espec\u00edfico, a biblioteca \u00e9 o lugar certo. Se voc\u00ea est\u00e1 procurando informa\u00e7\u00f5es sobre um\u2026","rel":"","context":"Em &quot;Not\u00edcias&quot;","block_context":{"text":"Not\u00edcias","link":"https:\/\/mundobibliotecario.com.br\/index.php\/category\/noticias\/"},"img":{"alt_text":"google vs biblioteca","src":"https:\/\/i0.wp.com\/mundobibliotecario.com.br\/wp-content\/uploads\/2022\/11\/this-or-that-1024x1024.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":8371,"url":"https:\/\/mundobibliotecario.com.br\/index.php\/2021\/01\/27\/biblioteca-da-universidade-ca-foscari-oferece-ferramenta-de-pesquisa-baseada-em-ia-para-estudantes-e-pesquisadores\/","url_meta":{"origin":5456,"position":5},"title":"Biblioteca da Universidade Ca &#8216;Foscari oferece ferramenta de pesquisa baseada em IA para estudantes e pesquisadores","author":"mundobibliotecario","date":"27\/01\/2021","format":false,"excerpt":"Fonte: Unsplash Yewno, um provedor l\u00edder de solu\u00e7\u00f5es de IA para a educa\u00e7\u00e3o, tem o prazer de anunciar que a Universidade Ca 'Foscari em Veneza fornecer\u00e1 a seus alunos e pesquisadores acesso ao Yewno Discover, a plataforma de pesquisa de intelig\u00eancia artificial carro-chefe da Yewno.\u00a0A Ca 'Foscari integrar\u00e1 o Yewno\u2026","rel":"","context":"Em &quot;Not\u00edcias&quot;","block_context":{"text":"Not\u00edcias","link":"https:\/\/mundobibliotecario.com.br\/index.php\/category\/noticias\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/mundobibliotecario.com.br\/wp-content\/uploads\/2021\/01\/markus-winkler-tGBXiHcPKrM-unsplash-1.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]}],"jetpack_likes_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pcbzwa-1q0","_links":{"self":[{"href":"https:\/\/mundobibliotecario.com.br\/index.php\/wp-json\/wp\/v2\/posts\/5456","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mundobibliotecario.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mundobibliotecario.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mundobibliotecario.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/mundobibliotecario.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=5456"}],"version-history":[{"count":1,"href":"https:\/\/mundobibliotecario.com.br\/index.php\/wp-json\/wp\/v2\/posts\/5456\/revisions"}],"predecessor-version":[{"id":5752,"href":"https:\/\/mundobibliotecario.com.br\/index.php\/wp-json\/wp\/v2\/posts\/5456\/revisions\/5752"}],"wp:attachment":[{"href":"https:\/\/mundobibliotecario.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=5456"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mundobibliotecario.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=5456"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mundobibliotecario.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=5456"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}