{"id":618,"date":"2009-05-11T09:21:35","date_gmt":"2009-05-11T12:21:35","guid":{"rendered":"http:\/\/mundobibliotecario.wordpress.com\/?p=618"},"modified":"2009-05-11T09:21:35","modified_gmt":"2009-05-11T12:21:35","slug":"seminario-sobre-gestao-eletronica-de-documentos-tendencias-e-aplicacoes","status":"publish","type":"post","link":"https:\/\/mundobibliotecario.com.br\/index.php\/2009\/05\/11\/seminario-sobre-gestao-eletronica-de-documentos-tendencias-e-aplicacoes\/","title":{"rendered":"Semin\u00e1rio sobre Gest\u00e3o Eletr\u00f4nica de Documentos: Tend\u00eancias e Aplica\u00e7\u00f5es"},"content":{"rendered":"<p>Vit\u00f3ria, Esp\u00edrito Santo<br \/>\nLocal do Evento: FAESA &#8211; Audit\u00f3rio  &#8211; Av. Vit\u00f3ria &#8211; Vit\u00f3ria &#8211; ES<br \/>\nHor\u00e1rio do Evento: de 09:00 \u00e0s 17:30 horas<br \/>\n25 e 26 de junho de 2009<\/p>\n<p>Palestra de abertura:<br \/>\nTend\u00eancias e mercado na implanta\u00e7\u00e3o de projetos de GED Metodologia para processos, organiza\u00e7\u00e3o documental e implanta\u00e7\u00e3o de ECM<br \/>\nMauricio Ant\u00f4nio Ferreira &#8211; S\u00e3o Paulo, Diretor de Tecnologia do CENADEM (SP)<\/p>\n<p>Palestra: Certifica\u00e7\u00e3o Digital:  Conceitos, Aplicabilidades, Casos de Uso e Abordagem para Viabiliza\u00e7\u00e3o  na Migra\u00e7\u00e3o  de Documentos e Processos em Suporte Papel para Eletr\u00f4nicos com Seguran\u00e7a, Validade Jur\u00eddica e Efic\u00e1cia Probat\u00f3ria:<br \/>\nStefano Kubi\u00e7a &#8211; Paran\u00e1 &#8211; MsC, Consultor de Certifica\u00e7\u00e3o Digital.<\/p>\n<p>Palestra: Preserva\u00e7\u00e3o digital &#8211; Estrat\u00e9gias para prote\u00e7\u00e3o e acesso aos documentos eletr\u00f4nicos<br \/>\nRos\u00e2ngela Cunha &#8211; Rio de Janeiro &#8211;  A Comandante  foi chefe do Departamento de Arquivos da Marinha, institui\u00e7\u00e3o com  o sistema de arquivos com mais de 100 anos de funcionamento.<\/p>\n<p>Palestra: E-ARQ: Modelo de Requisitos para Sistemas Informatizados de Gest\u00e3o Arquivistica de Documentos:<br \/>\nClaudia Lacombe Rocha &#8211; Rio de Janeiro &#8211;  Presidente da C\u00e2mara T\u00e9cnica de Documentos Eletr\u00f4nicos (CTDE), do Conselho Nacional de Arquivos (CONARQ)<\/p>\n<p>Palestra: Implanta\u00e7\u00e3o do Projeto de GED  on-line na CLARO.O case de GED\/ECM na Claro: o projeto, a implementa\u00e7\u00e3o, os impactos e li\u00e7\u00f5es aprendidas<br \/>\nS\u00f4nia Stropa &#8211; S\u00e3o Paulo &#8211; Administradora de Empresas e Web Design.<\/p>\n<p>Palestra: A \u00aeevolu\u00e7\u00e3o digital no Poder Judici\u00e1rio &#8211; Sistema de processos eletr\u00f4nicos do Esp\u00edrito Santo &#8211;  E-process:<br \/>\nLuciano Costa Bragatto &#8211; Esp\u00edrito Santo &#8211; Luciano Costa Bragatto \u00e9 Juiz de Direito no Estado do Esp\u00edrito Santo<\/p>\n<p>Palestra: GED para Empresas P\u00fablicas e Privadas<br \/>\nVanderlei Batista dos Santos &#8211; Bras\u00edlia &#8211; Arquivista, mestre em Ci\u00eancia da Informa\u00e7\u00e3o<\/p>\n<p>Palestra:  Implantando o Governo eletr\u00f4nico<br \/>\nVictor Murad Filho &#8211; Esp\u00edrito Santo -Diretor Presidente do Prodest<\/p>\n<p>Palestra:  Implanta\u00e7\u00e3o do Projeto de GED na \u00e1rea de Recursos Humanos da Unidade da unidade Petrobras no Esp\u00edrito Santo<br \/>\nSamyra Vieira Freitas &#8211; Esp\u00edrito Santo &#8211; Bibliotec\u00e1ria,  Informa\u00e7\u00e3o  e<br \/>\nDocumenta\u00e7\u00e3o  T\u00e9cnica da Ger\u00eancia de Tecnologia da Informa\u00e7\u00e3o  e<br \/>\nTelecomunica\u00e7\u00f5es  de  E&amp;P  da PETROBR\u00c1S no Esp\u00edrito Santo<\/p>\n<p>Palestra:  Arcelor Mittal Tubar\u00e3o:  implanta\u00e7\u00e3o de GED e compartilhamento do sucesso obtido<br \/>\nJos\u00e9 Marcos Pedro &#8211; Esp\u00edrito Santo &#8211; Coordenador da \u00e1rea de Gest\u00e3o Documental da Arcelor Mittal Tubar\u00e3o<\/p>\n<p>Informa\u00e7\u00f5es e Inscri\u00e7\u00f5es para o evento:<\/p>\n<p>Vit\u00f3ria, 25 e 26 de junho de 2009<br \/>\nPelos telefones (27) 3223-4537  (14.00 h \u00e0s 18.00 h) ou (27) 9249-2367<br \/>\nPelo e-mail:  ged2009es@gmail.com<\/p>\n<p>Pagamento<\/p>\n<p>Profissional &#8211; Empresarial ou Individual R$ 355,00 R$ 455,00 R$ 555,00<br \/>\nEstudante de P\u00f3s &#8211; gradua\u00e7\u00e3o  R$ 205,00 R$ 255,00 R$ 355,00<br \/>\nEstudante de Gradua\u00e7\u00e3o  R$ 65,00 R$ 105,00 R$ 125,00<\/p>\n<p>Ver mais em:<br \/>\nhttp:\/\/www.enara.org.br\/modules.php?name=News&#038;file=article&#038;sid=680<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Vit\u00f3ria, Esp\u00edrito Santo Local do Evento: FAESA &#8211; Audit\u00f3rio &#8211; Av. Vit\u00f3ria &#8211; Vit\u00f3ria &#8211; ES Hor\u00e1rio do Evento: de 09:00 \u00e0s 17:30 horas 25 e 26 de junho de 2009 Palestra de abertura: Tend\u00eancias e mercado na implanta\u00e7\u00e3o de projetos de GED Metodologia para processos, organiza\u00e7\u00e3o documental e implanta\u00e7\u00e3o de ECM Mauricio Ant\u00f4nio Ferreira &#8230; <a title=\"Semin\u00e1rio sobre Gest\u00e3o Eletr\u00f4nica de Documentos: Tend\u00eancias e Aplica\u00e7\u00f5es\" class=\"read-more\" href=\"https:\/\/mundobibliotecario.com.br\/index.php\/2009\/05\/11\/seminario-sobre-gestao-eletronica-de-documentos-tendencias-e-aplicacoes\/\" aria-label=\"Read more about Semin\u00e1rio sobre Gest\u00e3o Eletr\u00f4nica de Documentos: Tend\u00eancias e Aplica\u00e7\u00f5es\">Ler mais<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_mi_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"_jetpack_newsletter_access":"","footnotes":""},"categories":[27],"tags":[390],"class_list":["post-618","post","type-post","status-publish","format-standard","hentry","category-eventos","tag-gestao-eletronica-de-documentos"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack-related-posts":[{"id":4888,"url":"https:\/\/mundobibliotecario.com.br\/index.php\/2011\/11\/09\/seminario-gedeim-alianca-estrategica-de-governanca-corporativa-gestao-de-informacoes-2\/","url_meta":{"origin":618,"position":0},"title":"Semin\u00e1rio GED\/EIM &#8211; Alian\u00e7a Estrat\u00e9gica de Governan\u00e7a Corporativa &#038; Gest\u00e3o de Informa\u00e7\u00f5es","author":"mundobibliotecario","date":"09\/11\/2011","format":false,"excerpt":"O evento GED\/EIM 2011 Salvador ser\u00e1 a PRIMEIRA edi\u00e7\u00e3o baiana e a DECIMA TERCEIRA edi\u00e7\u00e3o nacional. Organizado em dois dias, o conte\u00fado proposto ser\u00e1 apresentado por Palestrantes de renome nacional e vem para inventariar a experi\u00eancia na defini\u00e7\u00e3o do papel da informa\u00e7\u00e3o nas empresas, p\u00fablicas e privadas, com a proposta\u2026","rel":"","context":"Em &quot;Eventos&quot;","block_context":{"text":"Eventos","link":"https:\/\/mundobibliotecario.com.br\/index.php\/category\/eventos\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":2310,"url":"https:\/\/mundobibliotecario.com.br\/index.php\/2011\/11\/09\/seminario-gedeim-alianca-estrategica-de-governanca-corporativa-gestao-de-informacoes\/","url_meta":{"origin":618,"position":1},"title":"Semin\u00e1rio GED\/EIM &#8211; Alian\u00e7a Estrat\u00e9gica de Governan\u00e7a Corporativa &#038; Gest\u00e3o de Informa\u00e7\u00f5es","author":"mundobibliotecario","date":"09\/11\/2011","format":false,"excerpt":"O evento GED\/EIM 2011 Salvador ser\u00e1 a PRIMEIRA edi\u00e7\u00e3o baiana e a DECIMA TERCEIRA edi\u00e7\u00e3o nacional. Organizado em dois dias, o conte\u00fado proposto ser\u00e1 apresentado por Palestrantes de renome nacional e vem para inventariar a experi\u00eancia na defini\u00e7\u00e3o do papel da informa\u00e7\u00e3o nas empresas, p\u00fablicas e privadas, com a proposta\u2026","rel":"","context":"Em &quot;Eventos&quot;","block_context":{"text":"Eventos","link":"https:\/\/mundobibliotecario.com.br\/index.php\/category\/eventos\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1945,"url":"https:\/\/mundobibliotecario.com.br\/index.php\/2011\/04\/09\/palestra-gratuita-digitalizacao-de-documentos\/","url_meta":{"origin":618,"position":2},"title":"Palestra Gratuita: Digitaliza\u00e7\u00e3o de Documentos","author":"mundobibliotecario","date":"09\/04\/2011","format":false,"excerpt":"Palestra Gratuita \"Digitaliza\u00e7\u00e3o de Documentos: como fazer, quando e por onde come\u00e7ar? - PRESENCIAL \u00a0 Objetivos Investir em servi\u00e7os de digitaliza\u00e7\u00e3o de documentos para uma ampla gama de benef\u00edcios para seus neg\u00f3cios. O armazenamento de documentos, tais processos, peti\u00e7\u00f5es, ac\u00f3rd\u00e3o, recortes de jornais e revistas, boletim informativo etc, documentos produzidos\u2026","rel":"","context":"Em &quot;Eventos&quot;","block_context":{"text":"Eventos","link":"https:\/\/mundobibliotecario.com.br\/index.php\/category\/eventos\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":2339,"url":"https:\/\/mundobibliotecario.com.br\/index.php\/2011\/11\/27\/curso-gestao-de-documentos-eletronicos-arquivisticos\/","url_meta":{"origin":618,"position":3},"title":"Curso &#8211; Gest\u00e3o de Documentos Eletr\u00f4nicos Arquiv\u00edsticos","author":"mundobibliotecario","date":"27\/11\/2011","format":false,"excerpt":"Objetivo \u00a0\u00a0\u00a0\u00a0\u00a0Orientar usu\u00e1rios, em n\u00edvel operacional e gerencial, quanto ao tratamento da informa\u00e7\u00e3o eletr\u00f4nica, seja ela p\u00fablica ou privada, e os v\u00e1rios aspectos relacionados \u00e0 Gest\u00e3o de Documentos Eletr\u00f4nicos Arquiv\u00edsticos. P\u00fablico-alvo \u00a0\u00a0\u00a0\u00a0\u00a0Gerentes, coordenadores, supervisores e demais agentes envolvidos com a gest\u00e3o eletr\u00f4nica de documentos. Necessidade x Justificativa \u00a0\u00a0\u00a0\u00a0\u00a0Na sociedade contempor\u00e2nea\u2026","rel":"","context":"Em &quot;Curso&quot;","block_context":{"text":"Curso","link":"https:\/\/mundobibliotecario.com.br\/index.php\/category\/curso\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":3296,"url":"https:\/\/mundobibliotecario.com.br\/index.php\/2013\/11\/08\/seminario-debate-desafios-da-preservacao-de-documentos-em-meio-digital\/","url_meta":{"origin":618,"position":4},"title":"Semin\u00e1rio debate desafios da preserva\u00e7\u00e3o de documentos em meio digital","author":"mundobibliotecario","date":"08\/11\/2013","format":false,"excerpt":"Das 13h30 \u00e0s 17h30 do dia 11 de novembro ser\u00e1 realizado o terceiro\u00a0Semin\u00e1rio de Documentos em Meio Digital: da Produ\u00e7\u00e3o \u00e0 Preserva\u00e7\u00e3o\u00a0no Anfiteatro Altino Antunes, da Faculdade de Medicina Veterin\u00e1ria e Zootecnia (FMVZ) da USP. Realizado pela Vice-Reitoria Executiva de Administra\u00e7\u00e3o da Universidade em parceria com o Arquivo Geral da\u2026","rel":"","context":"Em &quot;Eventos&quot;","block_context":{"text":"Eventos","link":"https:\/\/mundobibliotecario.com.br\/index.php\/category\/eventos\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":900,"url":"https:\/\/mundobibliotecario.com.br\/index.php\/2009\/10\/07\/semana-inaugural-arquivo-publico-e-historico-de-sao-carlos\/","url_meta":{"origin":618,"position":5},"title":"SEMANA INAUGURAL \u2013 Arquivo P\u00fablico e Hist\u00f3rico de S\u00e3o Carlos","author":"mundobibliotecario","date":"07\/10\/2009","format":false,"excerpt":"FUNDA\u00c7\u00c3O PR\u00d3-MEM\u00d3RIA DE S\u00c3O CARLOS Data: 19 a 23\/10 \u2013 Local: Audit\u00f3rio \u201cOctavio Damiano\u201d \u2013 Esta\u00e7\u00e3o Cultura Pra\u00e7a Ant\u00f4nio Prado, s\/n \u2013 Centro \u2013 Antiga Esta\u00e7\u00e3o Ferrovi\u00e1ria Inscri\u00e7\u00f5es at\u00e9 16\/10 pelo e-mail: arquivo.fpm@saocarlos.sp.gov.br ou Tel.: (16) 3373.2700 (Mencionar a palestra\/mesa redonda que ir\u00e1 participar) Programa\u00e7\u00e3o segunda-feira (19\/10) 9h - Credenciamento\u2026","rel":"","context":"Em &quot;Eventos&quot;","block_context":{"text":"Eventos","link":"https:\/\/mundobibliotecario.com.br\/index.php\/category\/eventos\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_likes_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pcbzwa-9Y","_links":{"self":[{"href":"https:\/\/mundobibliotecario.com.br\/index.php\/wp-json\/wp\/v2\/posts\/618","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mundobibliotecario.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mundobibliotecario.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mundobibliotecario.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/mundobibliotecario.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=618"}],"version-history":[{"count":0,"href":"https:\/\/mundobibliotecario.com.br\/index.php\/wp-json\/wp\/v2\/posts\/618\/revisions"}],"wp:attachment":[{"href":"https:\/\/mundobibliotecario.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=618"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mundobibliotecario.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=618"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mundobibliotecario.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=618"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}