{"id":7843,"date":"2020-09-17T08:00:00","date_gmt":"2020-09-17T11:00:00","guid":{"rendered":"http:\/\/mundobibliotecario.com.br\/?p=7843"},"modified":"2020-09-15T22:33:19","modified_gmt":"2020-09-16T01:33:19","slug":"atualizacao-da-extensao-do-navegador-do-botao-do-google-academico","status":"publish","type":"post","link":"https:\/\/mundobibliotecario.com.br\/index.php\/2020\/09\/17\/atualizacao-da-extensao-do-navegador-do-botao-do-google-academico\/","title":{"rendered":"Atualiza\u00e7\u00e3o da extens\u00e3o do navegador do bot\u00e3o do Google Acad\u00eamico"},"content":{"rendered":"\n<p>O bot\u00e3o do Google Acad\u00eamico, lan\u00e7ado em 2015, fornece acesso f\u00e1cil ao Google Acad\u00eamico de qualquer p\u00e1gina da web.\u00a0Voc\u00ea pode us\u00e1-lo para encontrar texto completo na web ou na biblioteca da sua universidade, formatar refer\u00eancias em estilos de cita\u00e7\u00e3o amplamente usados, repetir uma pesquisa na web no Acad\u00eamico ou simplesmente procurar uma refer\u00eancia de um artigo.<\/p>\n\n\n\n<p>Estamos lan\u00e7ando uma atualiza\u00e7\u00e3o com v\u00e1rios novos recursos.&nbsp;A janela que se abre quando voc\u00ea clica no bot\u00e3o Acad\u00eamico costumava ser assim:<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/scholar.google.com\/intl\/en\/scholar\/images\/blog\/gsb-bm25-2015.png\" alt=\"\"\/><\/figure>\n\n\n\n<p>Adicionamos uma estrela &#8220;Salvar&#8221;, movemos o bot\u00e3o &#8220;Citar&#8221; ao lado dela e adicionamos bot\u00f5es de navega\u00e7\u00e3o de hist\u00f3rico \u00e0 barra de ferramentas inferior:<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/scholar.google.com\/intl\/en\/scholar\/images\/blog\/gsb-bm25-2020.png\" alt=\"\"\/><\/figure>\n\n\n\n<p>Agora voc\u00ea pode salvar o artigo para ler mais tarde &#8211; clique na pequena estrela azul embaixo do artigo para salv\u00e1-lo ou na grande estrela cinza na parte inferior para ver todos os artigos salvos em sua biblioteca do Acad\u00eamico.\u00a0O artigo \u00e9 salvo em sua conta do Google Acad\u00eamico acessada mais recentemente;\u00a0para usar um diferente, clique na foto da conta no canto superior direito.<\/p>\n\n\n\n<p>Tamb\u00e9m adicionamos um bot\u00e3o Voltar!&nbsp;Agora voc\u00ea pode desfazer facilmente refinamentos de consulta que n\u00e3o funcionaram e at\u00e9 mesmo recuperar a janela depois de fech\u00e1-la &#8211; basta abri-la novamente e clicar novamente.&nbsp;O hist\u00f3rico do bot\u00e3o Acad\u00eamico \u00e9 armazenado localmente no navegador por uma hora;&nbsp;clique na foto da conta no canto superior direito para apag\u00e1-la imediatamente.<\/p>\n\n\n\n<p>Por fim, aprimoramos a forma como o bot\u00e3o Acad\u00eamico identifica a p\u00e1gina da web que voc\u00ea est\u00e1 lendo.\u00a0Clicar no bot\u00e3o ao ler um artigo em PDF agora deve localizar o artigo no Google Acad\u00eamico, para que voc\u00ea possa cit\u00e1-lo, salv\u00e1-lo ou explorar artigos relacionados.\u00a0Se o bot\u00e3o do Google Acad\u00eamico n\u00e3o encontrar o artigo correto, selecione seu t\u00edtulo na p\u00e1gina da web.<\/p>\n\n\n\n<p>O Bot\u00e3o Acad\u00eamico est\u00e1 atualmente dispon\u00edvel para&nbsp;<a href=\"https:\/\/chrome.google.com\/webstore\/detail\/google-scholar-button\/ldipcbpaocekfooobnbcddclnhejkcpn\">Chrome<\/a>&nbsp;e&nbsp;<a href=\"https:\/\/addons.mozilla.org\/en-US\/firefox\/addon\/google-scholar-button\/\">Firefox<\/a>&nbsp;.<\/p>\n\n\n\n<p>Postado por Belinda Shi, Kyu Jin Hwang e Alex Verstak.<\/p>\n\n\n\n<p>***<\/p>\n\n\n\n<p>Tradu\u00e7\u00e3o livre do artigo <a href=\"https:\/\/scholar.googleblog.com\/2020\/09\/scholar-button-browser-extension-update.html\" target=\"_blank\" rel=\"noreferrer noopener\">Scholar Button browser extension update<\/a>, publicado no <a href=\"https:\/\/scholar.googleblog.com\/\" target=\"_blank\" rel=\"noreferrer noopener\">Google Scholar Blog<\/a>.<\/p>\n\n\n\n<p>Dispon\u00edvel em: <a href=\"https:\/\/scholar.googleblog.com\/2020\/09\/scholar-button-browser-extension-update.html\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/scholar.googleblog.com\/2020\/09\/scholar-button-browser-extension-update.html<\/a>. Acesso em: 15 set. 2020.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O bot\u00e3o do Google Acad\u00eamico, lan\u00e7ado em 2015, fornece acesso f\u00e1cil ao Google Acad\u00eamico de qualquer p\u00e1gina da web.\u00a0Voc\u00ea pode us\u00e1-lo para encontrar texto completo na web ou na biblioteca da sua universidade, formatar refer\u00eancias em estilos de cita\u00e7\u00e3o amplamente usados, repetir uma pesquisa na web no Acad\u00eamico ou simplesmente procurar uma refer\u00eancia de um &#8230; <a title=\"Atualiza\u00e7\u00e3o da extens\u00e3o do navegador do bot\u00e3o do Google Acad\u00eamico\" class=\"read-more\" href=\"https:\/\/mundobibliotecario.com.br\/index.php\/2020\/09\/17\/atualizacao-da-extensao-do-navegador-do-botao-do-google-academico\/\" aria-label=\"Read more about Atualiza\u00e7\u00e3o da extens\u00e3o do navegador do bot\u00e3o do Google Acad\u00eamico\">Ler mais<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_mi_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"_jetpack_newsletter_access":"","footnotes":""},"categories":[60],"tags":[1408,1202,1203],"class_list":["post-7843","post","type-post","status-publish","format-standard","hentry","category-noticias","tag-botao","tag-google-academico","tag-google-scholar"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack-related-posts":[{"id":4787,"url":"https:\/\/mundobibliotecario.com.br\/index.php\/2018\/06\/04\/como-usar-o-botao-do-google-academico\/","url_meta":{"origin":7843,"position":0},"title":"Como usar o bot\u00e3o do Google Acad\u00eamico","author":"mundobibliotecario","date":"04\/06\/2018","format":false,"excerpt":"O Google Acad\u00eamico \u00e9 uma das ferramentas mais utilizadas hoje para se fazer pesquisas. Sua principal vantagem \u00e9 ser uma ferramenta gratuita, diferentemente de bases de dados assinadas pelas bibliotecas das institui\u00e7\u00f5es de ensino superior. Por outro lado, nem sempre \u00e9 poss\u00edvel se certificar sobre a origem do conte\u00fado. N\u00e3o\u2026","rel":"","context":"Em &quot;Voc\u00ea sabia?&quot;","block_context":{"text":"Voc\u00ea sabia?","link":"https:\/\/mundobibliotecario.com.br\/index.php\/category\/voce-sabia\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":3710,"url":"https:\/\/mundobibliotecario.com.br\/index.php\/2015\/04\/16\/botao-do-google-academico-extensao-chrome\/","url_meta":{"origin":7843,"position":1},"title":"Bot\u00e3o do Google Acad\u00eamico &#8211; Extens\u00e3o Chrome","author":"mundobibliotecario","date":"16\/04\/2015","format":false,"excerpt":"Google lan\u00e7ou sua pr\u00f3pria extens\u00e3o chrome para encurtar o caminho entre navega\u00e7\u00e3o\/leitura e busca no Google Acad\u00eamico. A extens\u00e3o, que leva o nome de \"Bot\u00e3o do Google Acad\u00eamico\" funciona assim: durante a navega\u00e7\u00e3o em p\u00e1gina que contenha dados referenciais (nem todas as p\u00e1ginas) ou ap\u00f3s selecionar um termo\/t\u00edtulo em uma\u2026","rel":"","context":"Em &quot;Not\u00edcias&quot;","block_context":{"text":"Not\u00edcias","link":"https:\/\/mundobibliotecario.com.br\/index.php\/category\/noticias\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":4338,"url":"https:\/\/mundobibliotecario.com.br\/index.php\/2016\/09\/05\/como-indexar-seu-periodico-no-google-academico\/","url_meta":{"origin":7843,"position":2},"title":"Como indexar seu peri\u00f3dico no Google Acad\u00eamico","author":"mundobibliotecario","date":"05\/09\/2016","format":false,"excerpt":"https:\/\/youtu.be\/nbg11PB4bDs Como indexar seu Peri\u00f3dico no Google Acad\u00eamico Est\u00e1 republicado no canal YouTube da ABEC o v\u00eddeo com a proje\u00e7\u00e3o correta dos slides! A ABEC promoveu este hangout para auxiliar editores cient\u00edficos. Assista e compartilhe! Duvidas? Entre em contato > fale.conosco@abecbrasil.org.br Moderadora: Suely de Brito Clemente Soares (Secret\u00e1rio-Geral) Convidados: Gildenir\u2026","rel":"","context":"Em &quot;Not\u00edcias&quot;","block_context":{"text":"Not\u00edcias","link":"https:\/\/mundobibliotecario.com.br\/index.php\/category\/noticias\/"},"img":{"alt_text":"^F494016EECFB18F4C44294D8EEF56AD174410D5BDF88A7A69E^pimgpsh_fullsize_distr","src":"https:\/\/mundobibliotecario.files.wordpress.com\/2016\/09\/f494016eecfb18f4c44294d8eef56ad174410d5bdf88a7a69epimgpsh_fullsize_distr.jpg?w=350&h=200&crop=1","width":350,"height":200},"classes":[]},{"id":3976,"url":"https:\/\/mundobibliotecario.com.br\/index.php\/2015\/09\/28\/3-dicas-para-usar-a-wikipedia-na-pesquisa-academica\/","url_meta":{"origin":7843,"position":3},"title":"3 dicas para usar a Wikip\u00e9dia na pesquisa acad\u00eamica","author":"mundobibliotecario","date":"28\/09\/2015","format":false,"excerpt":"O uso da Wikipedia em trabalhos acad\u00eamicos ainda \u00e9 um assunto controverso, mas pode ser uma porta de entrada para isso. Veja como! 1. Veja as refer\u00eancias utilizadas Ficou na d\u00favida sobre a qualidade do texto? D\u00ea uma olhada nas refer\u00eancias usadas no verbete. Se estiverem listados mais sites institucionais\u2026","rel":"","context":"Em &quot;Not\u00edcias&quot;","block_context":{"text":"Not\u00edcias","link":"https:\/\/mundobibliotecario.com.br\/index.php\/category\/noticias\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":427,"url":"https:\/\/mundobibliotecario.com.br\/index.php\/2009\/03\/08\/buraco-negro-como-a-web-devora-a-historia\/","url_meta":{"origin":7843,"position":4},"title":"Buraco negro: como a Web devora a Hist\u00f3ria","author":"mundobibliotecario","date":"08\/03\/2009","format":false,"excerpt":"Por Eric Auchard LONDRES (Reuters) - Acad\u00eamicos, pesquisadores e at\u00e9 mesmo estudiosos da hist\u00f3ria do beisebol perceberam recentemente o desaparecimento de alguns arquivos de jornais mais antigos at\u00e9 h\u00e1 pouco dispon\u00edveis na Web. Os problemas surgiram depois que a PaperofRecord.com, uma cole\u00e7\u00e3o de mais de 20 milh\u00f5es de p\u00e1ginas de\u2026","rel":"","context":"Em &quot;Not\u00edcias&quot;","block_context":{"text":"Not\u00edcias","link":"https:\/\/mundobibliotecario.com.br\/index.php\/category\/noticias\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":3894,"url":"https:\/\/mundobibliotecario.com.br\/index.php\/2015\/09\/09\/listas-de-fontes-de-informacao-para-a-pesquisa-academica\/","url_meta":{"origin":7843,"position":5},"title":"Listas de fontes de informa\u00e7\u00e3o para a pesquisa acad\u00eamica","author":"mundobibliotecario","date":"09\/09\/2015","format":false,"excerpt":"Compartilho os links de duas listas com fontes de informa\u00e7\u00e3o para pesquisas acad\u00eamicas: 1) a primeira \u00e9\u00a0uma compila\u00e7\u00e3o de sites e bases de dados realizada por Marcus P. Zillman, da Virtual Private Library: Academic and Scholar Search Engines and Sources:\u00a0An Internet Annotated Link 2) a Wikipedia tamb\u00e9m disponibiliza uma lista\u2026","rel":"","context":"Em &quot;Not\u00edcias&quot;","block_context":{"text":"Not\u00edcias","link":"https:\/\/mundobibliotecario.com.br\/index.php\/category\/noticias\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_likes_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pcbzwa-22v","_links":{"self":[{"href":"https:\/\/mundobibliotecario.com.br\/index.php\/wp-json\/wp\/v2\/posts\/7843","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mundobibliotecario.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mundobibliotecario.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mundobibliotecario.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/mundobibliotecario.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=7843"}],"version-history":[{"count":2,"href":"https:\/\/mundobibliotecario.com.br\/index.php\/wp-json\/wp\/v2\/posts\/7843\/revisions"}],"predecessor-version":[{"id":7845,"href":"https:\/\/mundobibliotecario.com.br\/index.php\/wp-json\/wp\/v2\/posts\/7843\/revisions\/7845"}],"wp:attachment":[{"href":"https:\/\/mundobibliotecario.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=7843"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mundobibliotecario.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=7843"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mundobibliotecario.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=7843"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}